{"id":18242,"date":"2021-04-28T13:54:43","date_gmt":"2021-04-28T13:54:43","guid":{"rendered":"http:\/\/born2travel.it\/?p=18242"},"modified":"2021-07-08T06:25:36","modified_gmt":"2021-07-08T06:25:36","slug":"far-west","status":"publish","type":"post","link":"https:\/\/born2travel.it\/it\/far-west\/","title":{"rendered":"Stati Uniti &#8211; Alla scoperta del vecchio Far West"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18242\" class=\"elementor elementor-18242\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49dda18e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"49dda18e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14820ec5\" data-id=\"14820ec5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f21906 elementor-widget elementor-widget-menu-anchor\" data-id=\"62f21906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6722463b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6722463b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2809f8bb\" data-id=\"2809f8bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-430fa399 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"430fa399\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e851e1b\" data-id=\"4e851e1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1013b7c0 elementor-widget elementor-widget-heading\" data-id=\"1013b7c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Stati Uniti                                                                   \nFar West<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa93bbb elementor-widget elementor-widget-text-editor\" data-id=\"3aa93bbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><strong>Capitale:<br \/><\/strong>Washington<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Moneta:<br \/><\/strong>Dollaro<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Periodo migliore: <br \/><\/strong>C&#8217;\u00e8 una enorme differenza tra il clima delle regioni desertiche a sud (secco tutto l&#8217;anno, torrido in estate) e quello delle regioni a nord di San Francisco, dove piove abbondantemente tutto l&#8217;anno. In estate il sole riscalda le spiagge e i monti nord-occidentali, ma fa anche salire i prezzi. In inverno il sole \u00e8 caldo a sud, mentre si scia sulle Montagne Rocciose<\/p><p style=\"text-align: left;\" align=\"center\"><strong>In una parola: <br \/><\/strong>How ya doin&#8217;? (come va?)<\/p><p style=\"text-align: left;\" align=\"center\"><b>Vaccini:<br \/><\/b>Nessuno<\/p><p style=\"text-align: left;\" align=\"center\"><b>Avvertenze:<br \/><\/b>&#8211; L&#8217;aria condizionata \u00e8 spesso regolata al massimo: tenete un indumento caldo a portata di mano<br \/>&#8211; Se noleggiate un&#8217;auto, ricordate che le stazioni di servizio sono poche e distanti tra loro. <br \/>&#8211; Portate sempre con voi un&#8217;abbondante scorta d&#8217;acqua se viaggiate in auto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24e5c3c3\" data-id=\"24e5c3c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92f3d60 elementor-widget elementor-widget-image\" data-id=\"92f3d60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"436\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag-1024x558.png\" class=\"attachment-large size-large wp-image-18245\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag-1024x558.png 1024w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag-300x163.png 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag-768x418.png 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag-16x9.png 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/usa-flag.png 1102w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612632cd elementor-widget elementor-widget-image\" data-id=\"612632cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"429\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map-1024x549.jpg\" class=\"attachment-large size-large wp-image-18246\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map-1024x549.jpg 1024w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map-300x161.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map-768x412.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map-16x9.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/USA-map.jpg 1072w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c036b2 elementor-widget elementor-widget-text-editor\" data-id=\"12c036b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><strong>A tavola:<br \/><\/strong>Hamburger, pizza, patatine fritte e Coca cola! Nelle grandi citt\u00e0 l&#8217;offerta gastronomica \u00e8 pi\u00f9 varia per la presenza di tante culture, ma anche le cittadine pi\u00f9 piccole di solito hanno almeno un ristorante cinese o americano. Specialit\u00e0 interessanti sono le pietanze del Southwest che risentono dell&#8217;influenza messicana come i red chile e i green chile del New Mexico. Le porzioni sono abbondanti e nulla impedisce di ordinare un piatto da dividere.<\/p><p style=\"text-align: left;\" align=\"center\"><span style=\"font-weight: bold;\">Esperienze da vivere:<br \/><\/span>Passeggiare lungo il Grand Canyon Arizona) o il Bryce Canyon (Utah); Incontrare i nativi navajo nella Monument Valley e dormire in un hogan (abitazione tradizionale); Fare una puntata in uno dei mille casino di Las Vegas!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1805174f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1805174f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;mountains&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-349d6e27\" data-id=\"349d6e27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d8c6e94 elementor-widget elementor-widget-heading\" data-id=\"1d8c6e94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alla scoperta del vecchio Far West<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-110804d elementor-widget elementor-widget-heading\" data-id=\"110804d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5000 km in auto dal Colorado fino alla costa Pacifica attraverso Utah, Arizona, Nevada, i mitici parchi, le grandi citt\u00e0 fino alla California!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d718296 elementor-widget elementor-widget-text-editor\" data-id=\"5d718296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il Far West racchiude le regioni pi\u00f9 belle degli Stati Uniti in quell\u2019ampia striscia di terra fra l\u2019Oceano Pacifico e la Catena delle Montagne Rocciose che comprende gli stati di:\u00a0California, Arizona, Utah, Colorado, Wyoming, Idaho, Montana, Nevada.<\/p><p style=\"text-align: left;\">Il viaggio \u00e8 splendido, visiteremo i parchi pi\u00f9 belli e famosi degli Stati Uniti!<br \/>Tema fondamentale del viaggio \u00e8 la Natura e non tanto le citt\u00e0 dalle quali si cerca di scappare via pi\u00f9 rapidamente possibile, inoltre \u00e8 un vero viaggio &#8216;on the road&#8217; si tratta di percorrere quasi 5000 km lungo le classiche strade viste migliaia di volte nei films percorrendone pure alcune di quelle mitiche come la Route 66!<\/p><p style=\"text-align: left;\">Abbiamo noleggiato un\u2019auto a Denver, Colorado, e guidato, in poco pi\u00f9 di tre settimane, fino a San Francisco attraversando numerosi stati, dormendo nei classici motel on the road, passando attraverso decine e decine di cittadine con la piccola aiuola dinanzi casa, l&#8217;immancabile bandiera stelle e strisce sull&#8217;uscio e vivendo il sogno americano!<\/p><p style=\"text-align: left;\">Come tutti i nostri racconti, anche questo non pretende di essere una guida di viaggio ma solo un mezzo di ispirazione e spunto\u00a0 per un eventuale viaggio futuro!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76b8dd93 elementor-widget elementor-widget-text-editor\" data-id=\"76b8dd93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td colspan=\"2\" width=\"652\"><p>Il nostro itinerario suggerito (30 giorni)<\/p><\/td><\/tr><tr><td width=\"234\"><p>prima settimana:<\/p><\/td><td width=\"418\"><p>Denver, Arches NP, Moab, Bluff (visita a Dead Horse Point), Monument Valley, Canyon de Chelly (trekking)<\/p><\/td><\/tr><tr><td width=\"234\"><p>seconda settimana:<\/p><\/td><td width=\"418\"><p>\u00a0Grand Canyon (trekking e volo in elicottero), Horseshoe Bend, Antelope Canyon<\/p><\/td><\/tr><tr><td width=\"234\"><p>terza settimana:<\/p><\/td><td width=\"418\"><p>Powell Lake (visita diga), Hatch, Bryce Canyon (trekking), Las Vegas, Bishop, Bodie (visita alla citt\u00e0 fantasma), Merced<\/p><\/td><\/tr><tr><td width=\"234\"><p>quarta settimana:<\/p><\/td><td width=\"418\"><p>Yosemite NP (trekking), Mariposa Grove (visita alle sequoie), Fresno, Los Angeles, Santa Barbara, Malibu, Santa Monica, San Francisco<\/p><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67dc0f0c elementor-widget elementor-widget-heading\" data-id=\"67dc0f0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">02 giugno Denver (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a7305e elementor-widget elementor-widget-text-editor\" data-id=\"52a7305e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Un lungo volo intercontinentale ci porta nei leggendari Stati Uniti d&#8217;America!<br \/>Piccolo pit stop ad Atlanta prima di ripartire alla volta di Denver, Colorado da dove comincer\u00e0 questa nostra lunga avventura on the road che ci condurr\u00e0 fino alle coste pacifiche della California!<br \/>Ma siamo stanchi morti, crolliamo sui nostri letti king size del nostro primo motel americano!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37a071a8 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"37a071a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"37a071a8\" data-elementor-lightbox-title=\"denver (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgyODYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2RlbnZlci0xLmpwZyIsInNsaWRlc2hvdyI6IjM3YTA3MWE4In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1.jpg'><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"37a071a8\" data-elementor-lightbox-title=\"denver (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgyODcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2RlbnZlci0yLmpwZyIsInNsaWRlc2hvdyI6IjM3YTA3MWE4In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/denver-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0eda95d elementor-widget elementor-widget-heading\" data-id=\"0eda95d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">03 giugno Moab (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9536aae elementor-widget elementor-widget-text-editor\" data-id=\"9536aae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dalle cime innevate del Colorado, non siamo lontani dalla famosa Aspen, passiamo i 3000 metri di altitudine durante il lungo trasferimento che ci conduce nello Utah.<\/p><p style=\"text-align: left;\">La cosa buffa \u00e8 che eravamo tutti in infradito e canottiera mentre attorno a noi c\u2019erano solo cumuli di neve appena spazzata\u2026<br \/>Questi Stati Uniti non finiscono mai di stupirci.<\/p><p style=\"text-align: left;\">Solo poco dopo eravamo gi\u00e0 all\u2019interno del roccioso e desertico \u201cArches National Park\u201d.<\/p><p style=\"text-align: left;\">Percorriamo il lungo tragitto (Devils Garden Trail) fino alla sua estremit\u00e0 (Landscape Arch).<\/p><p style=\"text-align: left;\">Balanced Rock, un\u2019enorme roccia in bilico, ci ha riportato alla mente tutti i cartoni animati del mitico Willy il coyote e del suo fedele \u201cnemico\u201d Beep-Beep.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f8c23b elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"68f8c23b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-1.jpg\" alt=\"arches np (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-2.jpg\" alt=\"arches np (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-3.jpg\" alt=\"arches np (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-4.jpg\" alt=\"arches np (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-5.jpg\" alt=\"arches np (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-6.jpg\" alt=\"arches np (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-7.jpg\" alt=\"arches np (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/arches-np-8.jpg\" alt=\"arches np (8)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cffc517 elementor-widget elementor-widget-text-editor\" data-id=\"cffc517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Si riparte. Destinazione: Moab.<br \/>Questa piccola cittadina, famosa in passato per i ricchi giacimenti di uranio, ora riveste il ruolo secondario di \u201ccaravanserraglio\u201d per i tanti visitatori dei parchi della zona.<\/p><p style=\"text-align: left;\">Dormiamo nella \u201cGramma House\u201d, una classica casa tradizionale americana in legno con tanto di yard, BBQ e post box da film.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc5a7df elementor-widget elementor-widget-heading\" data-id=\"cc5a7df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">04 giugno Bluff (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23cb3ad9 elementor-widget elementor-widget-text-editor\" data-id=\"23cb3ad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Stile1\" align=\"center\"><div class=\"Stile1\" align=\"center\"><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Dopo una fugace colazione tipica americana in un distributore di carburante raggiungiamo il \u201cDead Horse Point\u201d, reso celebre dal finale del film \u201cThelma &amp; Louise\u201d o \u201cMission impossible II\u201d.<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Grandi rocce alternate ad ampi spazi desertici, lunghe lingue d\u2019asfalto che muoiono verso l\u2019infinito\u2026<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a38f668 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"7a38f668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7a38f668\" data-elementor-lightbox-title=\"dead horse point (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzMjAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2RlYWQtaG9yc2UtcG9pbnQtMS5qcGciLCJzbGlkZXNob3ciOiI3YTM4ZjY2OCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7a38f668\" data-elementor-lightbox-title=\"dead horse point (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzMjEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2RlYWQtaG9yc2UtcG9pbnQtMi5qcGciLCJzbGlkZXNob3ciOiI3YTM4ZjY2OCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7a38f668\" data-elementor-lightbox-title=\"dead horse point (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzMjIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2RlYWQtaG9yc2UtcG9pbnQtMy5qcGciLCJzbGlkZXNob3ciOiI3YTM4ZjY2OCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/dead-horse-point-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba220d9 elementor-widget elementor-widget-text-editor\" data-id=\"ba220d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Stile1\" align=\"center\"><div class=\"Stile1\" align=\"center\"><p style=\"text-align: left;\">La spettacolare \u201cMonument Valley\u201d ci ha proiettati improvvisamente all\u2019interno del set di un film di Sergio Leone. I miei compagni di viaggio cominciavano a trasformarsi, a mano a mano che entravamo nella valle in John Wayne o Butch Cassidy, le auto sembravano cavalli indomabili e spesso capitava di incontrare dei veri indiano Navajo.<br \/>Questi ultimi rappresentano una delle ultime trib\u00f9 ancora esistenti anche se, un po\u2019 come succede ai Maori in Nuova Zelanda, sono posti ai margini della societ\u00e0.<\/p><p style=\"text-align: left;\">Dovrebbero assolutamente tutelare queste popolazioni con le loro antiche e vecchie tradizioni, usi, costumi e lingue.<\/p><p style=\"text-align: left;\">La Monument Valley \u00e8 stupefacente.<br \/>Se hai visto qualche film western ti sembrer\u00e0 di conoscerla da una vita! <br \/>M\u2019incantavo quando lasciavo correre la mia immaginazione, improvvisamente trib\u00f9 di indiani cominciavano a materializzarsi davanti ad un fuoco di bivacco e ai miei occhi stupiti\u2026<br \/>Vedevo cavalli selvaggi correre liberi, intere mandrie controllate da cow-boy con i classici cappelli e un fucile sempre pronto in mano\u2026 Capanne di pellirosse, frecce, pistole, carovane, saloon, la terra rossa\u2026<\/p><p style=\"text-align: left;\">La serata si conclude nella piccola cittadina di Mexican Hat, gustando dell\u2019ottime bistecconi di carne allo Swinging Steak.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-519afa9 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"519afa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-9.jpg\" alt=\"monument valley (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-4.jpg\" alt=\"monument valley (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-8.jpg\" alt=\"monument valley (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-5.jpg\" alt=\"monument valley (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-11.jpg\" alt=\"monument valley (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-12.jpg\" alt=\"monument valley (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-13.jpg\" alt=\"monument valley (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-14.jpg\" alt=\"monument valley (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/monument-valley-15.jpg\" alt=\"monument valley (15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa88769 elementor-widget elementor-widget-heading\" data-id=\"aa88769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">05 giugno Flagstaff (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6444408a elementor-widget elementor-widget-text-editor\" data-id=\"6444408a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il Canyon de Chelly \u00e8 una riserva indiana Navajo. <br \/>Proseguiamo fermandoci spesso lungo i vari spot per ammirare i tanti paesaggi che questo canyon riesce ad offrirci.<\/p><p style=\"text-align: left;\">\u201cSpider Rock\u201d \u00e8 un punto panoramico da cui si gode una vista molto suggestiva. Al centro vi \u00e8 una formazione rocciosa dalla forma di un grande spillone, sembra mancare ogni prospettiva\u2026 Non distingui dove finisce il cielo, dove la montagna, le colline circostanti, tutto si trasforma a seconda del punto di osservazione.<\/p><p style=\"text-align: left;\">Molto intenso il trek che ci ha condotti da White House Windows a White House Ruins, un paio di ore con forti pendenze\u2026 i 36 gradi si sentivano tutti!<br \/>Non c\u2019\u00e8 nulla da fare, adoro camminare nella natura, in qualunque forma essa si rappresenti.<\/p><p style=\"text-align: left;\">In serata raggiungiamo Flagstaff, famosa perch\u00e9 qui passa la leggendaria Route 66 oltre per la sua leggendaria ferrovia da cui transitano treni merci formati da decine e decine di convogli!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15d53bd6 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"15d53bd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"15d53bd6\" data-elementor-lightbox-title=\"canyon de chelly (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzNDksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2Nhbnlvbi1kZS1jaGVsbHktMS5qcGciLCJzbGlkZXNob3ciOiIxNWQ1M2JkNiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"15d53bd6\" data-elementor-lightbox-title=\"canyon de chelly (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzNTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2Nhbnlvbi1kZS1jaGVsbHktMi5qcGciLCJzbGlkZXNob3ciOiIxNWQ1M2JkNiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/canyon-de-chelly-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06b72fe elementor-widget elementor-widget-heading\" data-id=\"06b72fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">06 giugno Grand Canyon (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-363ff412 elementor-widget elementor-widget-text-editor\" data-id=\"363ff412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il Grand Canyon \u00e8 una meraviglia della natura unico nel suo genere. Le spaccature delle sue rocce mostrano tutta la vita del nostro Pianeta\u2026 sin dalla notte dei tempi.<br \/>E\u2019 impressionante. Con un solo sguardo non riesci a cogliere tutta la sua interezza e grandiosit\u00e0 perci\u00f2 suggerirei, se il tempo e il portafoglio lo permettono, di fare un volo in elicottero al fine di appezzare da un punto di vista privilegiato quest\u2019ennesima meraviglia!<\/p><p style=\"text-align: left;\">Il trek sull\u2019orlo del Canyon \u00e8 sorprendente. Suggerirei di trascorrere almeno tre giorni qui per poter viverlo pi\u00f9 intensamente grazie ai suoi numerosi tragitti.<br \/>A volte mi fermavo, in silenzio, ad ammirare quei precipizi senza prospettiva in cui il blu del fiume Colorado, che continua a scavare ancora la roccia, quasi stona con il rosso che domina tutto il paesaggio.<br \/>Mi fermavo a respirare il vento, a sentire i battiti di Nostra Madre Natura e ad ammirarla in tutta la sua intimit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3722765 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3722765\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-10.jpg\" alt=\"grand canyon (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-9.jpg\" alt=\"grand canyon (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-11.jpg\" alt=\"grand canyon (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-8.jpg\" alt=\"grand canyon (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-1.jpg\" alt=\"grand canyon (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-6.jpg\" alt=\"grand canyon (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/grand-canyon-7.jpg\" alt=\"grand canyon (7)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07f0c32 elementor-widget elementor-widget-heading\" data-id=\"07f0c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">07 giugno Powell Lake (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb0f845 elementor-widget elementor-widget-text-editor\" data-id=\"bb0f845\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Horseshoe Bend \u00e8 un\u2019ansa del fiume Colorado a forma di ferro di cavallo.<br \/>Sdraiato a pancia in gi\u00f9 sull\u2019orlo del precipizio ammiravo le maestose pareti rocciose che dalle viscere della terra s\u2019innalzavano alte nel cielo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41e862db elementor-widget elementor-widget-image\" data-id=\"41e862db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"horseshoe bend\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzNzgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2hvcnNlc2hvZS1iZW5kLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend.jpg\" class=\"attachment-full size-full wp-image-18378\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/horseshoe-bend-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-249a109a elementor-widget elementor-widget-text-editor\" data-id=\"249a109a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Antelope Canyon. Ultima riserva Navajo.<br \/>All\u2019interno ti sembra di essere dentro ad una lumaca magica.<br \/>E\u2019 un canyon antichissimo che ti permette di viverlo direttamente a contatto con la sua anima.<br \/>Un sentiero scavato tra le rocce dal vento e dalle inondazioni ha creato un passaggio molto caratteristico e quando la luce del sole\u00a0 riesce a filtrare lo spettacolo \u00e8 assicurato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96f91ba elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"96f91ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-8.jpg\" alt=\"antelope canyon (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-6.jpg\" alt=\"antelope canyon (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-7.jpg\" alt=\"antelope canyon (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-1.jpg\" alt=\"antelope canyon (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-2.jpg\" alt=\"antelope canyon (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-4.jpg\" alt=\"antelope canyon (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/antelope-canyon-5.jpg\" alt=\"antelope canyon (5)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737ea8ed elementor-widget elementor-widget-text-editor\" data-id=\"737ea8ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il lago Powell \u00e8 un lago artificiale formato dalle acque del fiume Colorado\u2026 Hanno impiegato ben 17 anni per dare vita a questa ennesima meraviglia.<br \/>Parlo di meraviglia perch\u00e9 in una zona cos\u00ec desertica uno specchio d\u2019acqua diventa prezioso.<br \/>Ma soprattutto perch\u00e9 grazie alla diga Glenn Canyon si offre corrente elettrica a tutto lo stato dello Utah. <br \/>Forza, si riparte per Hatch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c86eaa elementor-widget elementor-widget-image\" data-id=\"6c86eaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"powell lake\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgzOTksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL3Bvd2VsbC1sYWtlLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake.jpg\" class=\"attachment-full size-full wp-image-18399\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/powell-lake-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b001fc3 elementor-widget elementor-widget-heading\" data-id=\"b001fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">08 giugno Hatch (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-755d2217 elementor-widget elementor-widget-text-editor\" data-id=\"755d2217\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Hatch ha mantenuto tutto il fascino dell\u2019epoca western. Se invece di parcheggiare le nostre auto nel delizioso motel che ci ha ospitati per la notte avessimo lasciato i nostri cavalli a riposare non avrebbe stonato minimamente con il background.<\/p><p style=\"text-align: left;\">Bryce Canyon National Park \u00e8 celebre per gli hoodos, sono formazioni rocciose che svettano verso il cielo e che terminano con un masso sulla punta.<\/p><p style=\"text-align: left;\">Un sentiero che da uno spot di 8000 piedi (Sunrise point) scende verso il basso tra canyons e percorsi aridi.<\/p><p style=\"text-align: left;\">Manco il tempo di riposarci che si riparte verso Las Vegas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b5a803 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"77b5a803\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-10.jpg\" alt=\"bryce canyon (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-7.jpg\" alt=\"bryce canyon (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-1.jpg\" alt=\"bryce canyon (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-6.jpg\" alt=\"bryce canyon (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-2.jpg\" alt=\"bryce canyon (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-3.jpg\" alt=\"bryce canyon (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-5.jpg\" alt=\"bryce canyon (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-4.jpg\" alt=\"bryce canyon (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-8.jpg\" alt=\"bryce canyon (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bryce-canyon-9.jpg\" alt=\"bryce canyon (9)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6dfcc elementor-widget elementor-widget-heading\" data-id=\"ec6dfcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">09 giugno Las Vegas (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40705cd6 elementor-widget elementor-widget-text-editor\" data-id=\"40705cd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"stile1\" style=\"text-align: left;\" align=\"center\"><a href=\"\/las-vegas\" target=\"_blank\" rel=\"noopener\">Las Vegas<\/a> \u00e8 una citt\u00e0 unica nel suo genere.<br \/>Nata nel cuore del deserto, una <span style=\"color: windowtext; text-decoration: none; text-underline: none;\">Dubai<\/span> americana fatta di luci, suoni, finzioni e soldi.<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Sposarsi qui ha un senso diverso, \u00e8 come fare la spesa! La cosa buffa \u00e8 che un matrimonio celebrato qui ha valore legale al 100% in Italia ed altrove e diventa triste leggere le grandi pubblicit\u00e0 di avvocati al discount, forse anche le pratiche contrarie sono troppo facili.<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Proseguiamo lungo lo Strip, la lunga via del divertimento detta cos\u00ec dal fatto che i cosiddetti \u201cred eyes\u201d, i giocatori incalliti, spesso restano anche in mutande (to strip= spogliarsi)!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44ff2562 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"44ff2562\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"44ff2562\" data-elementor-lightbox-title=\"las vegas (13)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0MjcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy0xMy5qcGciLCJzbGlkZXNob3ciOiI0NGZmMjU2MiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-13.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"44ff2562\" data-elementor-lightbox-title=\"las vegas (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0MjUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy0xLmpwZyIsInNsaWRlc2hvdyI6IjQ0ZmYyNTYyIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"44ff2562\" data-elementor-lightbox-title=\"las vegas (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0MjYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy00LmpwZyIsInNsaWRlc2hvdyI6IjQ0ZmYyNTYyIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f25617e elementor-widget elementor-widget-text-editor\" data-id=\"5f25617e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Ceniamo al casino Luxor con un ottimo buffet in cui c&#8217;era ogni ben di Dio!<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Finalmente comincia il nostro tour. Attraversiamo tutti i vari hotel\/casino che con le loro luci ed attrazioni rendono questa citt\u00e0 cos\u00ec viva! Passiamo il \u201cNew York New York, Bellagio, Venetian, Palazzo, Luxor, Mirage\u201d ecc<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Cerchiamo di giocare alla roulette del casino Venetian ma troppo caro per noi (25$ a puntata!)<br \/>Finiamo al Circus Circus!<br \/>Poco dopo sono dietro al tavolo verde!<br \/>Alle tre di notte, stanco morto e con la bellezza di 28$ vinti, mi distendo a letto!<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Confesso che l&#8217;aria che si respirava in giro mi ha lasciato molto interdetto!<br \/>Gente triste seduta davanti ad un monitor accompagnata da un drink o da una sigaretta premendo un pulsante e sognando una fortuna che quasi mai arriva!<\/p><p class=\"stile1\" style=\"text-align: left;\" align=\"center\">Ammetto anche che pur non essendo uno scommettitore o un giocatore d&#8217;azzardo, l\u00ec dentro, diventa cos\u00ec facile farsi catturare&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f59c79 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"17f59c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-3.jpg\" alt=\"las vegas (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-14.jpg\" alt=\"las vegas (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-12.jpg\" alt=\"las vegas (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-15.jpg\" alt=\"las vegas (15)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-2.jpg\" alt=\"las vegas (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-5.jpg\" alt=\"las vegas (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-7.jpg\" alt=\"las vegas (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-6.jpg\" alt=\"las vegas (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-9.jpg\" alt=\"las vegas (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-10.jpg\" alt=\"las vegas (10)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5cae4 elementor-widget elementor-widget-heading\" data-id=\"3b5cae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">10 giugno Bishop (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19452e8b elementor-widget elementor-widget-text-editor\" data-id=\"19452e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Alle otto del mattino siamo gi\u00e0 pronti per ripartire.<br \/>Le luci dei grandi neon non brillano pi\u00f9, non ci sono ispanici ad ogni angolo della strada che ti riempiono di bigliettini pubblicitari con mille donne nude che si offrono per sesso, non c&#8217;\u00e8 il fiume di gente che scorre lungo lo Strip&#8230;<br \/>E&#8217; passata un&#8217;altra notte, migliaia e migliaia di dollari sono passati da una mano all&#8217;altra&#8230;<br \/>Tante persone hanno gioito, molte di pi\u00f9 pianto, qualcuno ha cambiato la vita, ma ora tutto tace&#8230;<br \/>Nessuna paura: tra qualche ora tutto ricomincia!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262a2494 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"262a2494\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"262a2494\" data-elementor-lightbox-title=\"las vegas (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0NTEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy0xMS5qcGciLCJzbGlkZXNob3ciOiIyNjJhMjQ5NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-11.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"262a2494\" data-elementor-lightbox-title=\"las vegas (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0NTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy04LmpwZyIsInNsaWRlc2hvdyI6IjI2MmEyNDk0In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-8.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"262a2494\" data-elementor-lightbox-title=\"las vegas\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0NTIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2xhcy12ZWdhcy5qcGciLCJzbGlkZXNob3ciOiIyNjJhMjQ5NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/las-vegas.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60fd1e16 elementor-widget elementor-widget-text-editor\" data-id=\"60fd1e16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Death Valley. Mai nessun nome fu pi\u00f9 appropriato.<br \/>Pi\u00f9 ti avvicini e pi\u00f9 la temperatura sale&#8230;<\/p><p style=\"text-align: left;\">Cominciamo il nostro giro dallo Zabrinskie Point, un&#8217;altura dalla quale si gode del \u201csolito\u201d spettacolo incredibile. Una piana secca, una piana di morte.<br \/>Mi chiedo come riuscissero, tanti anni fa, a superare questi luoghi con le carovane trainate dai cavalli e senza le attrezzature hi-tech di oggi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-320c6237 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"320c6237\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-1.jpg\" alt=\"death valley (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-2.jpg\" alt=\"death valley (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-3.jpg\" alt=\"death valley (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-5.jpg\" alt=\"death valley (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-4.jpg\" alt=\"death valley (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-9.jpg\" alt=\"death valley (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley.jpg\" alt=\"death valley\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7109b4b elementor-widget elementor-widget-text-editor\" data-id=\"7109b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Badwater Basin, una depressione a circa 86 metri sotto il livello del mare. C&#8217;\u00e8 un tappeto di sale e il termometro del mio orologio si ferma a 44,8\u00b0.<br \/>Manca il fiato e si suda copiosamente.<\/p><p style=\"text-align: left;\">In serata arriviamo a Bishop. Siamo in California!<\/p><p style=\"text-align: left;\">Momenti di tensione quando apprendiamo che l&#8217;ingresso Est allo Yosemite (Tioga Pass) \u00e8 chiuso per neve. Cerchiamo diverse alternative che ci avvicinino alla nostra meta.<br \/>Lavoriamo duramente per modificare i programmi iniziali. \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52eeb920 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"52eeb920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-6' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"52eeb920\" data-elementor-lightbox-title=\"death valley (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0NjQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2RlYXRoLXZhbGxleS03LmpwZyIsInNsaWRlc2hvdyI6IjUyZWViOTIwIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-7.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"52eeb920\" data-elementor-lightbox-title=\"death valley (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0NjUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2RlYXRoLXZhbGxleS04LmpwZyIsInNsaWRlc2hvdyI6IjUyZWViOTIwIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/death-valley-8.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d77854f elementor-widget elementor-widget-heading\" data-id=\"d77854f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">11 giugno Merced (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15e17f elementor-widget elementor-widget-text-editor\" data-id=\"15e17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Come temevamo la Sierra Nevada ci ha negato il suo accesso e quando Madre Natura si schiera contro di noi non possiamo fare altro che ubbidire.<\/p><p style=\"text-align: left;\">Questa deviazione ci costa circa 8 ore di strada in pi\u00f9, gli Stati Uniti sono davvero enormi!<br \/>Il paesaggio della California, tuttavia, \u00e8 cos\u00ec vario e soprattutto inaspettato che questo cambiamento di programma diventa motivo di nuove scoperte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fd2bdd elementor-widget elementor-widget-image\" data-id=\"6fd2bdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"bodie (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0ODAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JvZGllLTQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4.jpg\" class=\"attachment-full size-full wp-image-18480\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-4-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70758431 elementor-widget elementor-widget-text-editor\" data-id=\"70758431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Decidiamo di fermarci a Bodie, una citt\u00e0 fantasma abbandonata che si svilupp\u00f2 all&#8217;inizio del secolo scorso dopo che alcuni cercatori d&#8217;oro avevano trovato alcune pepite&#8230;<br \/>Il villaggio \u00e8 stato conservato in perfetto stato cos\u00ec come quando fu abbandonato. <br \/>E\u2019 surreale passeggiare tra quelle vecchie baracche di legno&#8230; e pensare che fino a qualche decennio fa c&#8217;erano carovane, banditi, cercatori di taglie, saloon&#8230; <br \/>Allora il Far West \u00e8 esistito davvero?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43760f8d gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"43760f8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-7' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43760f8d\" data-elementor-lightbox-title=\"bodie (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0ODMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JvZGllLTMuanBnIiwic2xpZGVzaG93IjoiNDM3NjBmOGQifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43760f8d\" data-elementor-lightbox-title=\"bodie (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0ODIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JvZGllLTIuanBnIiwic2xpZGVzaG93IjoiNDM3NjBmOGQifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43760f8d\" data-elementor-lightbox-title=\"bodie (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0ODEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JvZGllLTEuanBnIiwic2xpZGVzaG93IjoiNDM3NjBmOGQifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/bodie-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fac23 elementor-widget elementor-widget-heading\" data-id=\"45fac23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">12 giugno Fresno (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106c9bc1 elementor-widget elementor-widget-text-editor\" data-id=\"106c9bc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il paesaggio cambia completamente. Diventa alpino!<br \/>Si sale sempre di pi\u00f9, alberi secolari e sempreverdi si innalzano verso l&#8217;alto, ruscelli, cascate cominciano ad apparire ovunque&#8230; <br \/>Finalmente siamo nello Yosemite National Park! <br \/>Ci fermiamo nei vari spot per cercare di rubare qualche immagine con le nostre macchine fotografiche, almeno ci proviamo!<\/p><p style=\"text-align: left;\">Percorriamo qualche miglio all&#8217;interno del bosco attenti ai puma e agli orsi per vedere qualche cascata o punto panoramico&#8230;<br \/>La vegetazione \u00e8 cos\u00ec folta che non ti permette neppure il cielo blu. Ti avvolge completamente.<\/p><p style=\"text-align: left;\">Purtroppo ci sono troppe cose da vedere ed il tempo \u00e8 davvero poco quindi non riusciamo a godere di quei paesaggi e dei silenzi come avremmo desiderato.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8097c71 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"8097c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-8' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8097c71\" data-elementor-lightbox-title=\"yosemite (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0OTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL3lvc2VtaXRlLTEuanBnIiwic2xpZGVzaG93IjoiODA5N2M3MSJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8097c71\" data-elementor-lightbox-title=\"yosemite (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0OTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL3lvc2VtaXRlLTIuanBnIiwic2xpZGVzaG93IjoiODA5N2M3MSJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ddeb7a4 elementor-widget elementor-widget-text-editor\" data-id=\"7ddeb7a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Nel tardo pomeriggio approdiamo al Mariposa Grove, foresta famosa per la presenza di sequoie millenarie. Ce ne sono alcune di 2700 anni!<\/p><p style=\"text-align: left;\">Ci sentiamo come delle formiche al cospetto di questi giganti della natura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a4db9 elementor-widget elementor-widget-image\" data-id=\"41a4db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"yosemite (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg0OTYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL3lvc2VtaXRlLTMuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3.jpg\" class=\"attachment-full size-full wp-image-18496\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/yosemite-3-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1f02f elementor-widget elementor-widget-heading\" data-id=\"9a1f02f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">13 giugno Los Angeles (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dcb094 elementor-widget elementor-widget-text-editor\" data-id=\"5dcb094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Una citt\u00e0 davvero speciale!<br \/>Sin dalla highway cominci a leggere le indicazioni verso luoghi a noi noti da sempre: Hollywood, Beverly Hills, Melrose, Rodeo Drive&#8230;<br \/>Entri in citt\u00e0 e mille luci, insegne pubblicitarie luccicanti, fiumi di persone che corrono e scorrono ovunque.<br \/>Vedi le cose pi\u00f9 strane: un tipo con un vecchio parruccone sulla testa che sedeva ad un tavolino del McDonald leggendo un quotidiano e con al suo fianco una bambola gonfiabile tutta truccata.<\/p><p style=\"text-align: left;\">Il tour della citt\u00e0 comincia da un punto panoramico da cui si pu\u00f2 ammirare la celebre scritta: \u201cHollywood\u201d sulla collina. Ci accompagna Susan, una gossip woman di primo ordine: \u201cqui dove Brad Pitt fu scoperto da un talent scout quando lavorava come venditore di polli allo spiedo, qui dove Paris Hilton fu arrestata per guida in stato di ebbrezza&#8221;.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41f947b7 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"41f947b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-9' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41f947b7\" data-elementor-lightbox-title=\"los angeles (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MDcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2xvcy1hbmdlbGVzLTIuanBnIiwic2xpZGVzaG93IjoiNDFmOTQ3YjcifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"41f947b7\" data-elementor-lightbox-title=\"hollywood\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MTIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2hvbGx5d29vZC5qcGciLCJzbGlkZXNob3ciOiI0MWY5NDdiNyJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hollywood.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-200f8ab3 elementor-widget elementor-widget-text-editor\" data-id=\"200f8ab3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Beverly Hills<br \/>Entri in questo tranquillo quartiere alberato e ti sembra di essere in un film.<br \/>La prima cosa che ti viene in mente \u00e8 l&#8217;omonimo telefilm della nostra adolescenza con Brandon e Brenda ma in realt\u00e0 \u00e8 un falso cinematografico visto che \u00e8 stato girato a Pasadena, non lontano da qui.<br \/>Ci\u00f2 che \u00e8 vero, reale e tangibile sono le tante ville delle star americane.<br \/>Domina la vallata la villa di Spielberg con tanto di piazzola elicottero&#8230; Il resto \u00e8 tutta una serie di ville iper protette e sorvegliate che dall&#8217;esterno sembrano abbandonate.<br \/>\u201cQui vive Eddie Murphy, qui Jennifer Aniston, qui Brad Pitt, qui George Clooney, qui Tommy Hilfiger&#8230;&#8221; Ti fa quasi sorridere vedere che Britney Spears abita di fronte a Justin Timberlake e accanto a Madonna e immagini&#8230; ti finisce il caff\u00e8 e chiedi al vicino?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73589d15 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"73589d15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-10' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"73589d15\" data-elementor-lightbox-title=\"beverly hills (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MTksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JldmVybHktaGlsbHMtMS5qcGciLCJzbGlkZXNob3ciOiI3MzU4OWQxNSJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"73589d15\" data-elementor-lightbox-title=\"beverly hills (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MjAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JldmVybHktaGlsbHMtMi5qcGciLCJzbGlkZXNob3ciOiI3MzU4OWQxNSJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"73589d15\" data-elementor-lightbox-title=\"beverly hills (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MjEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2JldmVybHktaGlsbHMtMy5qcGciLCJzbGlkZXNob3ciOiI3MzU4OWQxNSJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/beverly-hills-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ac85a3 elementor-widget elementor-widget-text-editor\" data-id=\"0ac85a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Ci fermiamo un po&#8217; a Rodeo Drive, quartiere famoso per lo shopping, per poi finire a Melrose oggi vivo pi\u00f9 che mai per il gay pride!<\/p><p style=\"text-align: left;\">Giungiamo al Kodak Theatre, famoso perch\u00e8 l\u00ec avviene la consegna degli oscar&#8230; ma attenzione! Cos&#8217;\u00e8 quella folla l\u00ec? Un passante disinteressato mi dice pacatamente che c&#8217;\u00e8 solo Jim Carey che sta presentando il suo ultimo film e dopo un po&#8217; eccolo in giacca verde tra i flash dei fotografi a pochi metri da noi!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39b4e9ac gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"39b4e9ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-11' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"39b4e9ac\" data-elementor-lightbox-title=\"los angeles (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MzIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2xvcy1hbmdlbGVzLTQuanBnIiwic2xpZGVzaG93IjoiMzliNGU5YWMifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"39b4e9ac\" data-elementor-lightbox-title=\"los angeles (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1MzEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL2xvcy1hbmdlbGVzLTMuanBnIiwic2xpZGVzaG93IjoiMzliNGU5YWMifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/los-angeles-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf35ec8 elementor-widget elementor-widget-text-editor\" data-id=\"4cf35ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">In metro raggiungiamo facilmente gli Universal Studios.<br \/>Quanti films avremo visto che cominciavano con quel celebre logo?<br \/>L&#8217;interno \u00e8 un mondo a parte, ci perdiamo tra le vie di Universal Village tra artisti di strada e luci colorate.<\/p><p style=\"text-align: left;\">La serata termina lungo la \u201cWalk of fame\u201d, quella delle stelle sul marciapiede e dei calchi delle mani delle star hollywoodiane.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f9d5650 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6f9d5650\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hall-of-fame-4.jpg\" alt=\"hall of fame (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hall-of-fame-2.jpg\" alt=\"hall of fame (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hall-of-fame-3.jpg\" alt=\"hall of fame (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hall-of-fame-5.jpg\" alt=\"hall of fame (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/hall-of-fame-1.jpg\" alt=\"hall of fame (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab0026 elementor-widget elementor-widget-heading\" data-id=\"0ab0026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">14 giugno Santa Barbara (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6744c485 elementor-widget elementor-widget-text-editor\" data-id=\"6744c485\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Decidiamo di dedicare tutta la mattinata alle celeberrime spiagge californiane, da Venice di Baywatch a Santa Monica fino a Malibu.<\/p><p style=\"text-align: left;\">Nel pomeriggio ripartiamo alla volta della deliziosa Santa Barbara e nel frattempo spunta anche il sole.<br \/>Un porticciolo colorato, un viale alberato pieno di negozi e di giovani ci d\u00e0 il benvenuto!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3061682 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"3061682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-12' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3061682\" data-elementor-lightbox-title=\"malibu (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS0yLmpwZyIsInNsaWRlc2hvdyI6IjMwNjE2ODIifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3061682\" data-elementor-lightbox-title=\"malibu (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS0zLmpwZyIsInNsaWRlc2hvdyI6IjMwNjE2ODIifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e09fee elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"0e09fee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Viaggiare \u00e8 continua trasformazione, \u00e8 la metamorfosi del bruco che ogni giorno va a rosicchiare il solito cavolo e poi... per magia si trasforma e vola via come farfalla... e spazia su sentieri e paesi e ovunque trova meraviglia, ovunque trova persone e non gente... Viaggiare ti rallegra l'anima e ti fa tornare persona antica, pellegrino viandante sulle strade di una vita che ignori.\"\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Anonimo<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8e2d4a gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"2d8e2d4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-13' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2d8e2d4a\" data-elementor-lightbox-title=\"malibu (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS0xLmpwZyIsInNsaWRlc2hvdyI6IjJkOGUyZDRhIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2d8e2d4a\" data-elementor-lightbox-title=\"malibu (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS00LmpwZyIsInNsaWRlc2hvdyI6IjJkOGUyZDRhIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2d8e2d4a\" data-elementor-lightbox-title=\"malibu (5)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS01LmpwZyIsInNsaWRlc2hvdyI6IjJkOGUyZDRhIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-5.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36f6aaf elementor-widget elementor-widget-heading\" data-id=\"36f6aaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">15 giugno San Francisco (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-511f1f08 elementor-widget elementor-widget-text-editor\" data-id=\"511f1f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Ecco l&#8217;America che mi aspettavo e la incontro a San Francisco.<br \/>Un&#8217;immensa citt\u00e0 piena di mall, gente di ogni tipo per strada, gang di rappers neri, homeless ogni 50 metri, obesi che camminano con grossi panini grassosi, artisti di strada, predicatori&#8230;<\/p><p style=\"text-align: left;\">Qui trascorriamo due giorni come cani sciolti cercando di ammirare quanto pi\u00f9 possibile di questa grande citt\u00e0 californiana.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc435f gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"ebc435f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-14' class='gallery galleryid-18242 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ebc435f\" data-elementor-lightbox-title=\"san francisco\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NzYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL3Nhbi1mcmFuY2lzY28uanBnIiwic2xpZGVzaG93IjoiZWJjNDM1ZiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"ebc435f\" data-elementor-lightbox-title=\"san francisco (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NzUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL3Nhbi1mcmFuY2lzY28tMS5qcGciLCJzbGlkZXNob3ciOiJlYmM0MzVmIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb067d elementor-widget elementor-widget-text-editor\" data-id=\"9bb067d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Fisherman Wharf con la sua folla di turisti, i suoi ristoranti di pesce e granchi; Chinatown e la sua comunit\u00e0 cinese, pi\u00f9 volte ho avuto l&#8217;impressione di gironzolare per Hong Kong; Union Square, il cuore della citt\u00e0, il luogo dove si concentrano alberghi di lusso, grandi magazzini, boutique e negozi di vario genere e capolinea della Cable Car, uno spettacolo imperdibile; Castro, fulcro della cultura gay di San Francisco; Golden Gate Bridge, con i suoi possenti pilastri arancioni, sicuramente il simbolo della citt\u00e0. Percorrerlo a piedi in tutta la sua lunghezza di 2,7 km \u00e8 veramente emozionante poter toccare con mano le colossali misure e godere della vista della citt\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c5cba86 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3c5cba86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-3.jpg\" alt=\"san francisco (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-2.jpg\" alt=\"san francisco (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-6.jpg\" alt=\"san francisco (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-4.jpg\" alt=\"san francisco (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-5.jpg\" alt=\"san francisco (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-9.jpg\" alt=\"san francisco (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-10.jpg\" alt=\"san francisco (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/san-francisco-7.jpg\" alt=\"san francisco (7)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf53af elementor-widget elementor-widget-heading\" data-id=\"6cf53af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16 giugno San Francisco (USA)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5318d5 elementor-widget elementor-widget-text-editor\" data-id=\"e5318d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dal molo 33 ci imbarchiamo per l&#8217;interessante visita al penitenziario di Alcatraz.<\/p><p style=\"text-align: left;\">Per 30 anni \u00e8 stato il carcere pi\u00f9 duro degli Stati Uniti, tra gli ospiti pi\u00f9 famosi c&#8217;\u00e8 stato addirittura Al Capone. La visita \u00e8 ben organizzata anche grazie all&#8217;ausilio delle audioguide che riescono a valorizzare ancor di pi\u00f9 un luogo cos\u00ec particolare e che consiglio fortemente di noleggiare.<\/p><p style=\"text-align: left;\">L&#8217;isola che ospita il penitenziario giace a soli due km dalla terraferma e tranne per una fuga storica \u00e8 stata sempre considerata inespugnabile.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aee8b8f gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"aee8b8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-15' class='gallery galleryid-18242 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aee8b8f\" data-elementor-lightbox-title=\"alcatraz (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2FsY2F0cmF6LTMuanBnIiwic2xpZGVzaG93IjoiYWVlOGI4ZiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aee8b8f\" data-elementor-lightbox-title=\"alcatraz (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2FsY2F0cmF6LTIuanBnIiwic2xpZGVzaG93IjoiYWVlOGI4ZiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"aee8b8f\" data-elementor-lightbox-title=\"alcatraz (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDVcL2FsY2F0cmF6LTEuanBnIiwic2xpZGVzaG93IjoiYWVlOGI4ZiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/05\/alcatraz-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76a9ece elementor-widget elementor-widget-text-editor\" data-id=\"76a9ece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Questo meraviglioso viaggio volge al termine, con gli occhi ancora sognanti pensi che se abbracci la parete di un canyon senti che respira, se guardi lungo le spaccature delle montagne vedi gli indiani, li senti ululare e la polvere che si scorge in lontananza \u00e8 sicuramente quella dei loro cavalli che corrono al galoppo, se ti sposti di qualche miglio puoi scorgere Brad Pitt che incontra Thelma &amp; Louise in un fast food prima che le due si lancino dal Death Horse Point. E beep beep? Corre insieme alla nostra macchina inseguito da Willy il coyote. Bambi insieme all&#8217;orso Yoghi, Cip e Ciop che giocano tra i nostri piedi&#8230; ci sono proprio tutti. E poi succede che l&#8217;immaginazione non ti serve pi\u00f9 perch\u00e8 c&#8217;\u00e8 Jim Carey che ti saluta dall&#8217;altro lato della strada e passeggiando arrivi a casa di Brad Pitt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b604c69 elementor-widget elementor-widget-image\" data-id=\"b604c69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"malibu (6)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1NTksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDRcL21hbGlidS02LmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6.jpg\" class=\"attachment-full size-full wp-image-18559\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/04\/malibu-6-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14285100\" data-id=\"14285100\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-182d0e01 elementor-widget elementor-widget-shortcode\" data-id=\"182d0e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"single\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a047c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a047c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d5e688\" data-id=\"7d5e688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4a9c79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b4a9c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iscriviti alla TRAVEL LETTER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ed75c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"12ed75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"186\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"12ed75c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"St Vincent &amp; the Grenadines - Magie caraibiche a St Vincent\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"5880\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAccetto la Privacy & Coockie Policy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Spuntando questo campo accetti la nostra Privacy &amp; Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. &lt;a href=&quot;https:\/\/www.bor2travel.it\/privacy-policy\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Leggi di pi\u00f9 cliccando QUI&lt;\/a&gt;\" id=\"form-field-message-0\" name=\"form_fields[message]\" required=\"required\"> <label for=\"form-field-message-0\">Spuntando questo campo accetti la nostra Privacy & Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. <a href=\"https:\/\/www.bor2travel.it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 cliccando QUI<\/a><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96f05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac96f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da428a5 elementor-widget elementor-widget-heading\" data-id=\"da428a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Restiamo connessi!!!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537d25 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3537d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d94fa2b\" href=\"https:\/\/www.instagram.com\/born2travel.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c434c3d\" href=\"https:\/\/www.facebook.com\/Born2travelit\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-75693d7\" href=\"https:\/\/www.youtube.com\/channel\/UCXjLtjiN1TpNgwwNMupe08g\/featured?view_as=subscriber\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tripadvisor elementor-repeater-item-a9d1575\" href=\"https:\/\/www.tripadvisor.co.uk\/Profile\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tripadvisor<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-58816f5\" href=\"https:\/\/twitter.com\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22354f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22354f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c34d34 elementor-widget elementor-widget-heading\" data-id=\"0c34d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">Assicurazione di viaggio: \n\nmai partire senza!\nNoi consigliamo: Chapka!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b38e43 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3b38e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"150\" src=\"http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png\" class=\"attachment-large size-large wp-image-23587\" alt=\"\" srcset=\"http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png 153w, http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka-12x12.png 12w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2c124 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3c2c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">sconto del 10% <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc07bc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc07bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07cf481 elementor-widget elementor-widget-heading\" data-id=\"07cf481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.instagram.com\/born2travel.it\">Seguici su INSTAGRAM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817df7 elementor-widget elementor-widget-shortcode\" data-id=\"b817df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>Questo errore \u00e8 visibile solamente agli amministratori WordPress<\/span><br\/>\n\t\t\t<p><strong>Errore: Nessun feed trovato.<\/strong>\n\t\t\t<p>Vai alla pagina delle impostazioni del feed di Instagram per creare un feed.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210cc6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"210cc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f08535 elementor-widget elementor-widget-heading\" data-id=\"4f08535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Born2travel - VIDEO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf5def elementor-widget elementor-widget-video\" data-id=\"0bf5def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_k7oz8Hnxhk&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82826af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82826af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef49e70 elementor-widget elementor-widget-heading\" data-id=\"ef49e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ultimi Articoli dal Blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006a30 elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"0006a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31634 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-macao tag-asia tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-macao tag-travel tag-travel-with-kids\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/macao\/\">\n\t\t\t\tMacao in due giorni: Tra fascino portoghese e luci da &#8220;Las Vegas d&#8217;Oriente&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31467 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-calcutta category-ganges category-india category-indian-ocean category-kolkata category-travel category-travel-with-kids tag-asia tag-backpacking tag-born2travel-it tag-born2travelit tag-calcutta tag-kolkata tag-mother-teresa tag-sundarbans tag-tigers tag-travel tag-west-bengala\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/calcutta\/\">\n\t\t\t\tCalcutta &#8211; Il battito profondo dell&#8217;India\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29309 post type-post status-publish format-standard has-post-thumbnail hentry category-africa category-albania category-almaty category-argentina category-backpacking-around-the-world category-baku category-bali category-bangkok category-born2travel category-born2travel-it category-born2travelit category-brasile category-bristol category-budapest category-cina category-citta-europee category-cracovia category-dolomiti category-europa category-europe category-firenze category-francia category-greece category-grenada category-honeymoon category-hong-kong category-indonesia category-islanda category-italia category-parigi category-ryadh category-st-moritz category-stati-uniti category-travel category-travel-with-kids category-trentino-alto-adige category-turchia category-turkey category-tuscany tag-backpacking tag-born2travel-it tag-born2travelit tag-cruise tag-europa tag-europe tag-honeymoon tag-luxury tag-parigi tag-ryadh tag-st-moritz tag-travel tag-travel-in-europe tag-viaggi-lussuosi tag-volo-privato\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/fughe-di-lusso\/\">\n\t\t\t\tFughe di lusso: rotte dirette verso destinazioni d&#8217;\u00e9lite\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29234 post type-post status-publish format-standard has-post-thumbnail hentry category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-citta-europee category-madrid category-spagna tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-cose-da-fare-a-madrid tag-europa tag-europe tag-madrid tag-viaggio-a-madrid tag-viaggio-in-spagna tag-week-end-a-madrid\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/le-5-cose-migliori-da-fare-in-vacanza-a-madrid\/\">\n\t\t\t\tMadrid &#8211; Le 5 cose migliori da fare in vacanza a Madrid\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ca7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f16ca7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Stati Uniti Far West Capitale: Washington Moneta: Dollaro Periodo migliore:<\/p>\n","protected":false},"author":2,"featured_media":1055,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[103,104,120,121,122,621,41,173,83,163],"tags":[791,784,36,59,60,259,793,785,781,786,796,790,792,166,787,789,795,782,788,794,797,32,798,164,783],"class_list":["post-18242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backpacking","category-backpacking-around-the-world","category-born2travel","category-born2travel-it","category-born2travelit","category-couchsurfing","category-diari-di-viaggio","category-travel","category-travel-with-kids","category-usa","tag-antelope-canyon","tag-arizona","tag-backpacking","tag-born2travel","tag-born2travel-it","tag-born2travelit","tag-bryce-canyon","tag-california","tag-coast-to-coast","tag-colorado","tag-death-valley","tag-denver","tag-grand-canyon","tag-las-vegas","tag-los-angeles","tag-moab","tag-monument-valley","tag-nevada","tag-san-francisco","tag-santa-barbara","tag-stati-uniti","tag-travel","tag-united-states","tag-usa","tag-utah"],"_links":{"self":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/18242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/comments?post=18242"}],"version-history":[{"count":5,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/18242\/revisions"}],"predecessor-version":[{"id":19714,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/18242\/revisions\/19714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/media?parent=18242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/categories?post=18242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/tags?post=18242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}