{"id":16216,"date":"2020-12-29T09:08:23","date_gmt":"2020-12-29T09:08:23","guid":{"rendered":"http:\/\/born2travel.it\/?p=16216"},"modified":"2021-07-08T06:41:46","modified_gmt":"2021-07-08T06:41:46","slug":"nepal","status":"publish","type":"post","link":"https:\/\/born2travel.it\/it\/nepal\/","title":{"rendered":"Nepal &#8211; Namaste Himalaya"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16216\" class=\"elementor elementor-16216\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41724bde elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"41724bde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35440c8a\" data-id=\"35440c8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52a69063 elementor-widget elementor-widget-menu-anchor\" data-id=\"52a69063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c0132ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c0132ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c1be47a\" data-id=\"5c1be47a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-34c48297 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34c48297\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6b6c683\" data-id=\"6b6c683\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-496bf31a elementor-widget elementor-widget-heading\" data-id=\"496bf31a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nepal<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36190f3f elementor-widget elementor-widget-text-editor\" data-id=\"36190f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><strong>Capitale:<br \/><\/strong>Katmandu<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Moneta:<br \/><\/strong>Rupia<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Periodo migliore: <br \/><\/strong>Ottobre e novembre (subito dopo il monsone) sono i periodi pi\u00f9 piacevoli per visitare il Nepal e soprattutto per fare escursioni in montagna. Meglio evitare sia il periodo del monsone (da met\u00e0 giugno a settembre) sia l&#8217;inverno (da dicembre a febbraio), quando fa freddo quasi dappertutto. In alta quota serve un abbigliamento caldo durante tutto l&#8217;anno.<\/p><p style=\"text-align: left;\" align=\"center\"><strong>In una parola: <br \/><\/strong>Namaste (Mi inchino a te)<\/p><p style=\"text-align: left;\" align=\"center\"><b>Vaccini:<br \/><\/b>&#8211; La malaria \u00e8 presente tutto l&#8217;anno nelle aree rurali del Terai: solo in questa zona \u00e8 consigliata la profilassi antimalarica. E&#8217; diffusa anche la dengue.<br \/>&#8211; Durante il monsone, nei boschi bisogna guardarsi dalle sanguisughe, portate un pacchetto di sale: aiuta a farle staccare dalla pelle<br \/>&#8211; Soprattutto per chi fa escursioni in montagna il rischio di diarrea \u00e8 molto alto: usate tutte le precauzioni igieniche.<\/p><p style=\"text-align: left;\" align=\"center\"><strong>A tavola:<br \/><\/strong>Lontano dalle zone turistiche dovrete accontentarvi di daal bhaat (riso con lenticchie in umido), noodles, omelette e minestre istantanee. La carne (masu), piuttosto rara perch\u00e8 molti nepalesi sono vegetariani, si trova pi\u00f9 facilmente nella Valle di Katmandu. Assaggiate i momo (ravioli tibetani fritti o al vapore) e i piatti d&#8217;ispirazione cinese come i chow mein e noodles in brodo. Oltre ai dolci a base di latte e zucchero di palma provate il famoso juju dhau (il re degli yogurt) di Bhaktapur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5d044695\" data-id=\"5d044695\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65dd5c4b elementor-widget elementor-widget-image\" data-id=\"65dd5c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"203\" height=\"248\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-flag.png\" class=\"attachment-large size-large wp-image-16219\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-flag.png 203w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-flag-10x12.png 10w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef6e3a5 elementor-widget elementor-widget-image\" data-id=\"2ef6e3a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"594\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-map.jpg\" class=\"attachment-large size-large wp-image-16220\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-map.jpg 816w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-map-300x223.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-map-768x570.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/nepal-map-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5045b9 elementor-widget elementor-widget-text-editor\" data-id=\"7a5045b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><b>Avvertenze:<br \/><\/b>&#8211; Attenti alle guide fasulle che avvicinano gli stranieri nelle zone turistiche. Prenotate la guida tramite un&#8217;agenzia affidabile.<br \/>&#8211; E&#8217; sconsigliato portare i bambini di et\u00e0 inferiore a un anno al di sopra dei 1200 metri e i bambini hanno meno di 10 anni sopra i 3000 mt.\u00a0<br \/>&#8211; In media, tra i 7 e 8 anni, un bambino \u00e8 in grado di camminare 3 ore al giorno, alternando la marcia a tratti in cui \u00e8 trasportato (in una cesta di vimini!)<\/p><p style=\"text-align: left;\" align=\"center\"><span style=\"font-weight: bold;\">Esperienze da vivere:<br \/><\/span>Salire in cima al Sarangkot (1592 mt) per ammirare l&#8217;Annapurna, massiccio dell&#8217;Himalaya; Trekking facili e di pochi giorni con partenza dai dintorni di Katmandu; Facili uscite in kayak sul Lago Fewa a Pokhara; Girare in bici a Lumbini tra templi e pagode nella citt\u00e0 natale di Budda.<\/p><p style=\"text-align: left;\" align=\"center\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ec6e007 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ec6e007\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;mountains&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4e53eeb9\" data-id=\"4e53eeb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4381e269 elementor-widget elementor-widget-heading\" data-id=\"4381e269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Namaste Himalaya<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39283fc7 elementor-widget elementor-widget-heading\" data-id=\"39283fc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lasciatevi ammaliare dalla storia di Kathmandu, i ghat di Pashupatinath, lo stupa bianco di Bodnath, i templi di Bhaktapur fino al trekking sul sentiero dell\u2019 Annapurna.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ac374c7 elementor-widget elementor-widget-text-editor\" data-id=\"1ac374c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Disteso ai piedi delle maestose vette dell&#8217;Himalaya, il\u00a0Nepal \u00e8 una terra di antichi templi buddisti e ind\u00f9 e di paesaggi straordinari, solcati dai sentieri pi\u00f9 belli del mondo, \u00e8 la\u00a0meta per antonomasia per gli amanti del trekking e della montagna.<br \/>Un Paese mistico e misterioso che affascina e ammalia ancora moltissimo noi occidentali: economicamente povero ma ricco di inestimabili bellezze naturali, di cultura e di storia. Un luogo lontano dal tempo, con paesaggi puntellati di templi, piccoli villaggi antichi, viste mozzafiato sulle vette dell\u2019Himalaya e \u201cbandierine di preghiera\u201d agitate dal vento.\u00a0<br \/>Un Paese che, purtroppo, \u00e8 stato pesantemente colpito dal terremoto del 2015, e che ha bisogno pi\u00f9 che mai del turismo per riprendersi.<\/p><p class=\"Stile1\" style=\"text-align: left;\" align=\"center\">Partiamo, via terra, dalla capitale Kathmandu, con i suoi mille templi induisti e buddisti, e ci lasciamo rapire dall\u2019atmosfera rilassata e di pace dell\u2019area che circondata la cosiddetta \u201cvalle di Kathmandu\u201d, fino ai villaggi arroccati sui rilievi montuosi pi\u00f9 impervi del pianeta, come l\u2019Everest nell\u2019Himalaya e la catena dell\u2019Annapurna prima di dirigerci verso l\u2019India ma solo dopo aver salutato il villaggio natio di Buddha. Abbiamo utilizzato solo mezzi locali, vecchi autobus spesso molto scomodi e in compagnia di galline o capre lungo strade paesaggisticamente pittoresche ma non sempre sicure.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-582ce90f elementor-widget elementor-widget-text-editor\" data-id=\"582ce90f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td colspan=\"2\" width=\"652\"><p>Il nostro itinerario suggerito (18 giorni)<\/p><\/td><\/tr><tr><td width=\"234\"><p>sette giorni:<\/p><\/td><td width=\"418\"><p>Kathmandu (visita di Thamel Square, Durban Square, Santuario di Pashupatinath, Bodnath, Bhaktapur, Patan, tempio di Swayambunath)<\/p><\/td><\/tr><tr><td width=\"234\"><p>cinque giorni:<\/p><\/td><td width=\"418\"><p>da Chisapani a Nagarkot (trekking di cinque giorni con guida)<\/p><\/td><\/tr><tr><td width=\"234\"><p>quattro giorni:<\/p><\/td><td width=\"418\"><p>Pokhara, escursione sul lago Phewa Tal, scalata fino a Sarangkot<\/p><\/td><\/tr><tr><td width=\"234\"><p>due giorni:<\/p><\/td><td width=\"418\"><p>Lumbini (visita alla citt\u00e0 natale di Buddha), via terra fino al confine con l&#8217;<a href=\"\/northern-india\/\" target=\"_blank\" rel=\"noopener\">India<\/a><\/p><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10dec1f elementor-widget elementor-widget-heading\" data-id=\"10dec1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">24 settembre Kathmandu (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfa4303 elementor-widget elementor-widget-text-editor\" data-id=\"dfa4303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Katmandu, il\u00a0cuore economico e sociale del Paese, una citt\u00e0 moderna, ma allo stesso tempo custode delle tradizioni della cultura induista e buddista. <br \/>Diventata famosa in Occidente tra gli anni \u201960 e \u201970 come meta favorita degli hippies di ogni parte del mondo, si \u00e8 in seguito costruita una fama turistica di tutto rispetto, questo grazie al suo alto valore culturale che si esprime nei templi, negli antichi palazzi, nei maestosi stupa e nei monasteri.<\/p><p style=\"text-align: left;\">Vagando nel suo centro storico che porta alla mitica Durbar Square (dove Bernardo Bertolucci gir\u00f2 il \u201cPiccolo Buddha\u201d) si respira un\u2019atmosfera quasi medievale. <br \/>Durbar Square d\u00e0 l\u2019idea di ci\u00f2 che era questo piccolo regno nel passato.<br \/>Tanti piccoli santuari, pagode, templi hindu\u2026 basta chiudere gli occhi per farsi trasportare dalla fantasia in luoghi incantati lontani\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57f3804d gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"57f3804d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-16216 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"57f3804d\" data-elementor-lightbox-title=\"kathmandu (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYyNzgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2thdGhtYW5kdS0xLmpwZyIsInNsaWRlc2hvdyI6IjU3ZjM4MDRkIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1.jpg'><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"57f3804d\" data-elementor-lightbox-title=\"kathmandu (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYyNzksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2thdGhtYW5kdS0yLmpwZyIsInNsaWRlc2hvdyI6IjU3ZjM4MDRkIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ebe0186 elementor-widget elementor-widget-heading\" data-id=\"2ebe0186\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">25 settembre Kathmandu (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1728b919 elementor-widget elementor-widget-text-editor\" data-id=\"1728b919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il Tempio induista di Pashupatinath sorge sulle sponde del Fiume Bagmati e nel 1979 \u00e8 divenuto Patrimonio Mondiale dell&#8217;Umanit\u00e0 dell&#8217;UNESCO. Se visiti il sito a febbraio o a marzo, partecipa al festival Maha Shivaratri che attira al tempio oltre 70.000 persone.<\/p><p style=\"text-align: left;\">Questo \u00e8 il tempio dove il ciclo vitale giunge al termine e dove si trovano alcune aree destinate alle pire per la cremazione dei defunti.<\/p><p style=\"text-align: left;\">Mi ha fatto tanto tenerezza la scena di una coppia, avranno avuto la mia et\u00e0, dopo aver recitato tanti rituali strani, per noi occidentali, istruiti da un santone dai lunghi capelli rasta e con il classico \u201ctikal\u201d rosso sulla fronte, hanno raccolto tutti i resti del rito in una grossa foglia e con tanta speranza l\u2019hanno lasciata andare sulle ripide e sporche acque del fiume Bagmati.<\/p><p style=\"text-align: left;\">Vedere, per la prima volta, un corpo bruciare su un ghat mi ha fatto un certo effetto.<\/p><p style=\"text-align: left;\">E\u2019 proprio vera la frase: \u201cpolvere sei e polvere ritornerai\u201d.<br \/>Bambini innocenti si tuffavano nell\u2019acqua sporca del fiume, poche decine di metri piu\u2019 avanti ci si preparava per l\u2019ennesima cremazione.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ef0a57 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"45ef0a57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-11.jpg\" alt=\"pashupatinath (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-2.jpg\" alt=\"pashupatinath (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-10.jpg\" alt=\"pashupatinath (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-1.jpg\" alt=\"pashupatinath (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-3.jpg\" alt=\"pashupatinath (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-6.jpg\" alt=\"pashupatinath (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-12.jpg\" alt=\"pashupatinath (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-14.jpg\" alt=\"pashupatinath (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-4.jpg\" alt=\"pashupatinath (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-5.jpg\" alt=\"pashupatinath (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-7.jpg\" alt=\"pashupatinath (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-8.jpg\" alt=\"pashupatinath (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-9.jpg\" alt=\"pashupatinath (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pashupatinath-13.jpg\" alt=\"pashupatinath (13)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a94f564 elementor-widget elementor-widget-heading\" data-id=\"a94f564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">26 settembre Boudhanath (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-348dcf30 elementor-widget elementor-widget-text-editor\" data-id=\"348dcf30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Situato lungo un&#8217;antica via commerciale, questo luogo di meditazione \u00e8 una tappa obbligata per qualsiasi viaggio spirituale nell&#8217;area di Kathmandu. <br \/>Boudhanath \u00e8 una delle stupa pi\u00f9 grandi al mondo e da secoli molti mercanti e commercianti tibetani offrono le proprie preghiere a questa terra.<\/p><p style=\"text-align: left;\">Qui siamo proiettati letteralmente indietro nel tempo.<br \/>L\u2019enorme stupa bianca al centro del luogo sacro domina la scena. <br \/>Tutto attorno tante campane di ogni forma e oggetti sacri da far roteare in senso orario spingendoli con le mani, si dice che il loro movimento diffonda le preghiere e speranze deposte in esse!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef3ba54 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1ef3ba54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-16216 gallery-columns-4 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ef3ba54\" data-elementor-lightbox-title=\"bodnath (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JvZG5hdGgtMi5qcGciLCJzbGlkZXNob3ciOiIxZWYzYmE1NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ef3ba54\" data-elementor-lightbox-title=\"bodnath (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMTIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JvZG5hdGgtMS5qcGciLCJzbGlkZXNob3ciOiIxZWYzYmE1NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ef3ba54\" data-elementor-lightbox-title=\"bodnath (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JvZG5hdGgtMy5qcGciLCJzbGlkZXNob3ciOiIxZWYzYmE1NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1ef3ba54\" data-elementor-lightbox-title=\"bodnath (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMTUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JvZG5hdGgtNC5qcGciLCJzbGlkZXNob3ciOiIxZWYzYmE1NCJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bodnath-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-180ee5e elementor-widget elementor-widget-heading\" data-id=\"180ee5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">27 settembre Bhaktapur (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44040cfe elementor-widget elementor-widget-text-editor\" data-id=\"44040cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Stile1\" align=\"center\"><div class=\"Stile1\" align=\"center\"><p style=\"background: white; vertical-align: baseline; text-align: left;\"><span class=\"stile11\">Bhaktapur \u00e8 una delle tante citt\u00e0 stato dell\u2019area himalayana, un tempo fiorente, ora sfoggia i resti del suo antico splendore<\/span><\/p><p style=\"background: white; vertical-align: baseline; text-align: left;\"><span class=\"stile11\">Dichiarato\u00a0Patrimonio dell\u2019Umanit\u00e0 dall\u2019UNESCO, situato nei dintorni di Kathmandu, all\u2019interno dell\u2019area si trova anche il tempio di Nyatapola, la famosa\u00a0<a href=\"https:\/\/siviaggia.it\/idee-di-viaggio\/viaggio-tra-le-piazze-di-bhaktapur-cosa-vedere-in-nepal\/196465\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: windowtext; text-decoration: none; text-underline: none;\">piazza di Taumadhi<\/span><\/a>\u00a0e altri due edifici storici, il tempio di Dattatreya e Pujari.<\/span><\/p><p style=\"background: white; vertical-align: baseline; text-align: left;\"><span class=\"stile11\">Toccata dal sisma dell\u2019aprile 2015,\u00a0Bakthapur\u00a0\u00e8 stata in parte danneggiata dal terremoto, i quali segni sono ancora visibili, non tanto per gli edifici crollati (ce ne sono, incastonati tra quelli che hanno resistito alla scossa) ma pi\u00f9 per i tanti puntali piazzati a rinforzo della stabilit\u00e0 di templi e stupa che non si sono sgretolati, ma sulle cui facciate \u00e8 possibile vedere le crepe o le cicatrici di parti ornamentali cadute.<\/span><\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d4acca7 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"5d4acca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-16216 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5d4acca7\" data-elementor-lightbox-title=\"patan (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNDMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3BhdGFuLTEuanBnIiwic2xpZGVzaG93IjoiNWQ0YWNjYTcifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5d4acca7\" data-elementor-lightbox-title=\"bhaktapur (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMjgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JoYWt0YXB1ci0xLmpwZyIsInNsaWRlc2hvdyI6IjVkNGFjY2E3In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5d4acca7\" data-elementor-lightbox-title=\"bhaktapur (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzMzAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2JoYWt0YXB1ci0zLmpwZyIsInNsaWRlc2hvdyI6IjVkNGFjY2E3In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/bhaktapur-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33987c4 elementor-widget elementor-widget-heading\" data-id=\"33987c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">28 settembre Swayambhunath (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13118f90 elementor-widget elementor-widget-text-editor\" data-id=\"13118f90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Una tappa d\u2019obbligo \u00e8 l\u2019antico\u00a0tempio di Swayambhunath, anche chiamato\u00a0tempio delle scimmie, dove salire gli oltre 300 scalini di pietra per godere di uno dei panorami pi\u00f9 suggestivi della capitale del Nepal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63da5daf elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"63da5daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-5.jpg\" alt=\"swayambunath (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-1.jpg\" alt=\"swayambunath (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-2.jpg\" alt=\"swayambunath (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-3.jpg\" alt=\"swayambunath (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-4.jpg\" alt=\"swayambunath (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-7.jpg\" alt=\"swayambunath (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-16.jpg\" alt=\"swayambunath (16)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-15.jpg\" alt=\"swayambunath (15)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-8.jpg\" alt=\"swayambunath (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-9.jpg\" alt=\"swayambunath (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-10.jpg\" alt=\"swayambunath (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-11.jpg\" alt=\"swayambunath (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-12.jpg\" alt=\"swayambunath (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-13.jpg\" alt=\"swayambunath (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-14.jpg\" alt=\"swayambunath (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 16\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/swayambunath-17.jpg\" alt=\"swayambunath (17)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995ecd6 elementor-widget elementor-widget-text-editor\" data-id=\"995ecd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Infine ci fermiamo a Patan che ci accoglie con il suo maestoso palazzo reale, i suoi suggestivi vicoletti, le pagode e le statue dalle mille forme, odori, fumi, credenti devoti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75099ebf gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"75099ebf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-16216 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"75099ebf\" data-elementor-lightbox-title=\"patan (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNDQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3BhdGFuLTIuanBnIiwic2xpZGVzaG93IjoiNzUwOTllYmYifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"75099ebf\" data-elementor-lightbox-title=\"patan (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNDUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3BhdGFuLTMuanBnIiwic2xpZGVzaG93IjoiNzUwOTllYmYifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/patan-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6114f2cf elementor-widget elementor-widget-text-editor\" data-id=\"6114f2cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Ultimo giro nella zona di Thamel, con i suoi vicoli stretti e sempre molto affollati, dove si concentrano i ristoranti specializzati nella cucina tipica locale, i negozi per l\u2019attrezzatura di trekking, (occhio ai falsi della North Face) e le agenzie di viaggio. <br \/>Decidiamo di affidarci proprio ad una di esse per organizzare il nostro trekking lungo il percorso dell\u2019Annapurna in modo da avere una guida per i prossimi giorni into the wild! E\u2019 il consiglio che sento di dare a tutti in modo da favorire le agenzie locali e potere godere, senza pensieri e stress, dei mille trekking nella natura montana nepalese<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43d6bb70 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"43d6bb70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-16216 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43d6bb70\" data-elementor-lightbox-title=\"thamel (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNzgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3RoYW1lbC0yLmpwZyIsInNsaWRlc2hvdyI6IjQzZDZiYjcwIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43d6bb70\" data-elementor-lightbox-title=\"thamel (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNzcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3RoYW1lbC0xLmpwZyIsInNsaWRlc2hvdyI6IjQzZDZiYjcwIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"43d6bb70\" data-elementor-lightbox-title=\"thamel (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTYzNzksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3RoYW1lbC0zLmpwZyIsInNsaWRlc2hvdyI6IjQzZDZiYjcwIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/thamel-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-932a51f elementor-widget elementor-widget-heading\" data-id=\"932a51f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">29 settembre Chisapani (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c1bd297 elementor-widget elementor-widget-text-editor\" data-id=\"1c1bd297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Oggi lasciamo la capitale del Nepal, in questi giorni ci dedicheremo alla scoperta della natura himalayana\u2026<\/p><p style=\"text-align: left;\">Scrivere il diario dopo un trekking \u00e8 davvero \u201cliberatorio\u201d.<\/p><p style=\"text-align: left;\">Oggi dodici kilometri tra sentieri, salite e discese.<\/p><p style=\"text-align: left;\">A volte guardavo davanti e pensavo: \u201cnon ce la far\u00f2 mai ad arrivare in cima\u201d.<\/p><p style=\"text-align: left;\">Il fiato corto, le goccioline di sudore giu\u2019 dalla schiena, i muscoli tesi e noi, passo dopo passo, lasciavamo i kilometri alle spalle per immergerci nella natura piu\u2019 incontaminata. Il cinguettio degli uccelli, le farfalle che ti accompagnavano svolazzandoti attorno\u2026<\/p><p style=\"text-align: left;\">Comincia a piovere, ci ripariamo con delle grosse buste di plastica, proseguiamo fino ad un gruppo di bufali che ci sbarra la strada, improvvisamente il sole tramonta proprio quando decidiamo di fermarci a passare la notte in un villaggio molto spartano, dormiremo su delle panche in legno, fa molto freddo, siamo ancora bagnati ma felici! Il paesaggio circostante \u00e8 surreale\u2026 cerchiamo di respirare a pieni polmoni e a riempire i nostri occhi di tanta meraviglia!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e117cba elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"5e117cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-13.jpg\" alt=\"chisapani (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-1.jpg\" alt=\"chisapani (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-2.jpg\" alt=\"chisapani (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-4.jpg\" alt=\"chisapani (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-8.jpg\" alt=\"chisapani (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-6.jpg\" alt=\"chisapani (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-7.jpg\" alt=\"chisapani (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-9.jpg\" alt=\"chisapani (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-5.jpg\" alt=\"chisapani (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-10.jpg\" alt=\"chisapani (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-11.jpg\" alt=\"chisapani (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-12.jpg\" alt=\"chisapani (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-14.jpg\" alt=\"chisapani (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 14\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/chisapani-15.jpg\" alt=\"chisapani (15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a237fb9 elementor-widget elementor-widget-heading\" data-id=\"a237fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">30 settembre Nagarkot (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b88e68d elementor-widget elementor-widget-text-editor\" data-id=\"2b88e68d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Oggi le gambe hanno retto i sedici kilometri che separano Chisapani da Nagarkot<strong>.<\/strong><br \/>Questa notte ho dormito davvero poco. C\u2019era un\u2019umidit\u00e0 del 100% sulla panca di legno, coperte completamente bagnate, finestra rotta, bagno intasato\u2026<\/p><p style=\"text-align: left;\">La sveglia suona alle 6,45 e dopo un chapati con tanto miele ci mettiamo subito in cammino.<br \/>I primi dieci kilometri sono passati abbastanza velocemente, la strada era piacevole ed immersa nella natura, addirittura ne abbiamo approfittato per stendere i nostri vestiti bagnati sugli zaini a mo\u2019 di stendi panni ambulanti.<br \/>In tarda mattinata ci fermiamo un po\u2019 per mangiare qualcosina e riposare un po\u2019.<\/p><p style=\"text-align: left;\">Dopo un\u2019oretta dalla nostra ripartenza ecco che improvvisamente arriva un forte acquazzone, di nuovo, tutti inzuppati continuiamo imperterriti, dobbiamo raggiungere la nostra meta prima che faccia troppo buio.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e65764 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"2e65764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-6' class='gallery galleryid-16216 gallery-columns-4 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2e65764\" data-elementor-lightbox-title=\"nagarkot (1) (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25hZ2Fya290LTEtMS5qcGciLCJzbGlkZXNob3ciOiIyZTY1NzY0In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-1-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2e65764\" data-elementor-lightbox-title=\"nagarkot (2) (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MTUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25hZ2Fya290LTItMS5qcGciLCJzbGlkZXNob3ciOiIyZTY1NzY0In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-2-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2e65764\" data-elementor-lightbox-title=\"nagarkot (3) (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MTYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25hZ2Fya290LTMtMS5qcGciLCJzbGlkZXNob3ciOiIyZTY1NzY0In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-3-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"2e65764\" data-elementor-lightbox-title=\"nagarkot (4) (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MTcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25hZ2Fya290LTQtMS5qcGciLCJzbGlkZXNob3ciOiIyZTY1NzY0In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nagarkot-4-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77386a5 elementor-widget elementor-widget-heading\" data-id=\"77386a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">01 ottobre Sankhu (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cfbe4dd elementor-widget elementor-widget-text-editor\" data-id=\"5cfbe4dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Oggi dovrebbe essere il giorno pi\u00f9 easy di trek visti i soli 5-6 kilometri di strada ma il calore ed i sentieri sdrucciolevoli ci hanno fatto faticare abbastanza!<br \/>E\u2019 stato molto interessante attraversare i tanti piccoli villaggi a piedi, passo dopo passo, osservando, senza dar fastidio, la loro semplice quotidianit\u00e0.<\/p><p style=\"text-align: left;\">Arrivati a Sankhu, sudati fradici, in taxi ritorniamo a Kathmandu e durante il trasferimento gi\u00e0 mille immagini cominciavano a popolare la nostra mente: le salite, le bevute d\u2019acqua dalla borraccia, la pioggia, i sentieri di montagna, le fredde notti scomode nelle bettole, i paesaggi, le cime innevate, i \u201cnamaste\u201d dei bambini curiosi o dei vecchi stanchi. Ci sentiamo pieni!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b70bc5 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"7b70bc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-7' class='gallery galleryid-16216 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7b70bc5\" data-elementor-lightbox-title=\"sankhu (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MzEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhbmtodS0yLmpwZyIsInNsaWRlc2hvdyI6IjdiNzBiYzUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7b70bc5\" data-elementor-lightbox-title=\"sankhu (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MzAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhbmtodS0xLmpwZyIsInNsaWRlc2hvdyI6IjdiNzBiYzUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7b70bc5\" data-elementor-lightbox-title=\"sankhu (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MzIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhbmtodS0zLmpwZyIsInNsaWRlc2hvdyI6IjdiNzBiYzUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sankhu-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16f1537 elementor-widget elementor-widget-heading\" data-id=\"16f1537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">02 ottobre Kathmandu (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267bcd5f elementor-widget elementor-widget-text-editor\" data-id=\"267bcd5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Ritornati nella capitale, oggi cerchiamo di riorganizzare le idee in vista della seconda parte di questo viaggio emozionante alla scoperta del Nepal!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbd75a4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"bbd75a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-8' class='gallery galleryid-16216 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"bbd75a4\" data-elementor-lightbox-title=\"kathmandu (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NDAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2thdGhtYW5kdS00LmpwZyIsInNsaWRlc2hvdyI6ImJiZDc1YTQifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"bbd75a4\" data-elementor-lightbox-title=\"kathmandu (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0MzksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2thdGhtYW5kdS0zLmpwZyIsInNsaWRlc2hvdyI6ImJiZDc1YTQifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/kathmandu-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22d6129 elementor-widget elementor-widget-heading\" data-id=\"22d6129\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">03 ottobre Pokhara (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ec592c0 elementor-widget elementor-widget-text-editor\" data-id=\"3ec592c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Alle 6,30 del mattino partiamo in bus alla volta di Pokhara.<\/p><p style=\"text-align: left;\">Lasciare la capitale con il suo smog, il suo traffico tentacolare, la sua confusione, la sua sporcizia non ci \u00e8 dispiaciuto pi\u00f9 di tanto soprattutto dopo i giorni trascorsi completamente avvolti nella natura.<\/p><p style=\"text-align: left;\">A mano a mano che ci allontanavamo cambiava tutto il paesaggio circostante.<\/p><p style=\"text-align: left;\">Un verde sempre pi\u00f9 imponente cominciava a dominare la scena, alti monti, ruscelli, fiumi, boschi completavano il background.<\/p><p style=\"text-align: left;\">Pokhara, la \u201ccitt\u00e0 del laghi\u201d, come viene chiamata in Nepal, si trova\u00a0ai piedi del rilievo montuoso dell\u2019Annapurna, una tra le cime pi\u00f9 alte del mondo e (quasi)\u00a0impossibile da scalare.\u00a0Si tratta della seconda citt\u00e0 del Paese per importanza e dimensioni, situata ad un\u2019altezza dal livello del mare di circa 1.000 metri, nella\u00a0regione del Gandaki. <br \/>Pokhara \u00e8 una meta molto ambita dagli escursionisti, infatti vengono organizzate quotidianamente gite a piedi o in barca nello splendido territorio circostante, per vedere i bellissimi 7 laghi della zona.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf16049 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4bf16049\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-4.jpg\" alt=\"pokhara (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-3.jpg\" alt=\"pokhara (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-6.jpg\" alt=\"pokhara (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-5.jpg\" alt=\"pokhara (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-7.jpg\" alt=\"pokhara (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-2.jpg\" alt=\"pokhara (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-8.jpg\" alt=\"pokhara (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-9.jpg\" alt=\"pokhara (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-10.jpg\" alt=\"pokhara (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-11.jpg\" alt=\"pokhara (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-12.jpg\" alt=\"pokhara (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/pokhara-1.jpg\" alt=\"pokhara (1)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d58a0e elementor-widget elementor-widget-heading\" data-id=\"6d58a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">04 ottobre Sarangkot (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-790c9923 elementor-widget elementor-widget-text-editor\" data-id=\"790c9923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Nei pressi di Pokhara si trova il\u00a0villaggio di Sarangkot.<\/p><p style=\"text-align: left;\">Partenza di buon mattino per raggiungere la stazione dei bus locali.<br \/>Il nostro piccolo bus \u00e8 preso d\u2019assalto nel vero senso della parola. La gente sbucava da ogni angolo e veniva inghiottita dallo scatolone di latta!<br \/>Ero impalato tra 3-4 ragazzini da un lato, un\u2019intera famiglia dall\u2019altro, varie signore anziane alle spalle e altri 2-3 ragazzini davanti\u2026<\/p><p style=\"text-align: left;\">Improvvisamente sbuca pure una capretta tra le mie gambe che ogni tanto mi leccava e mordicchiava il polpaccio quasi a muovermi a compassione\u2026 poverina, forse sapeva che la stavano portando a sacrificare!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b49a985 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6b49a985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-9' class='gallery galleryid-16216 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6b49a985\" data-elementor-lightbox-title=\"sarangkot (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NjUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhcmFuZ2tvdC0xLmpwZyIsInNsaWRlc2hvdyI6IjZiNDlhOTg1In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6b49a985\" data-elementor-lightbox-title=\"nepal (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NzMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25lcGFsLTIuanBnIiwic2xpZGVzaG93IjoiNmI0OWE5ODUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6b49a985\" data-elementor-lightbox-title=\"nepal (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NzIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL25lcGFsLTEuanBnIiwic2xpZGVzaG93IjoiNmI0OWE5ODUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/nepal-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35387722 elementor-widget elementor-widget-text-editor\" data-id=\"35387722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il trasferimento Pokhara \u2013 Sarangkot \u00e8 molto folkloristico.<br \/>Finalmente all\u2019urlo di un tipo mezzo rasta il nostro bus si ferma, lottando conquistiamo l\u2019uscita. Siamo fuori!<br \/>Si respira! L\u2019aria \u00e8 pura, non c\u2019\u00e8 casino e siamo gli unici in giro.<br \/>Ci fermiamo subito in un punto panoramico ad ammirare la citt\u00e0 di Pokhara dall\u2019alto e il suo lago.<br \/>Ma si riparte presto: dobbiamo conquistare la cima!<\/p><p style=\"text-align: left;\">E\u2019 faticoso ma il panorama dall\u2019alto ci ripaga di tutte le fatiche.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3feaa840 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"3feaa840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-10' class='gallery galleryid-16216 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3feaa840\" data-elementor-lightbox-title=\"sarangkot (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NjYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhcmFuZ2tvdC0yLmpwZyIsInNsaWRlc2hvdyI6IjNmZWFhODQwIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3feaa840\" data-elementor-lightbox-title=\"sarangkot (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0NjcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL3NhcmFuZ2tvdC0zLmpwZyIsInNsaWRlc2hvdyI6IjNmZWFhODQwIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/sarangkot-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76b8fc4 elementor-widget elementor-widget-heading\" data-id=\"76b8fc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">06 ottobre Lumbini (Nepal)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46e70e3c elementor-widget elementor-widget-text-editor\" data-id=\"46e70e3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Comincia il nostro avvicinamento alla frontiera con l\u2019India ma prima decidiamo di fermarci in una cittadina molto particolare.<\/p><p style=\"text-align: left;\">Lumbini \u00e8 uno storico sito della tradizione buddista e si narra che sia il luogo dove la Regina Mayadevi diede alla luce Siddartha Gautama nel 623 a.C. <br \/>Lumbini \u00e8 un&#8217;area monastica e vanta numerosi monasteri da ammirare. Inoltre, la legge proibisce la costruzione di hotel e ristoranti nella zona e nelle immediate vicinanze.<\/p><p style=\"text-align: left;\">Ultima tappa nepalese prima di tuffarci per qualche mese nella caotica <a href=\"\/northern-india\/\" target=\"_blank\" rel=\"noopener\">India<\/a>\u2026 ma questa \u00e8 un\u2019altra storia!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a4f03ee gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6a4f03ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-11' class='gallery galleryid-16216 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6a4f03ee\" data-elementor-lightbox-title=\"lumbini (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0ODksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2x1bWJpbmktMi5qcGciLCJzbGlkZXNob3ciOiI2YTRmMDNlZSJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6a4f03ee\" data-elementor-lightbox-title=\"lumbini (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY0ODgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDNcL2x1bWJpbmktMS5qcGciLCJzbGlkZXNob3ciOiI2YTRmMDNlZSJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2021\/03\/lumbini-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-710a6659\" data-id=\"710a6659\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b496f80 elementor-widget elementor-widget-shortcode\" data-id=\"6b496f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"single\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a047c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a047c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d5e688\" data-id=\"7d5e688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4a9c79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b4a9c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iscriviti alla TRAVEL LETTER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ed75c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"12ed75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"186\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"12ed75c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Turkmenistan - Alla Porta dell&#039;Inferno\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"31000\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAccetto la Privacy & Coockie Policy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Spuntando questo campo accetti la nostra Privacy &amp; Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. &lt;a href=&quot;https:\/\/www.bor2travel.it\/privacy-policy\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Leggi di pi\u00f9 cliccando QUI&lt;\/a&gt;\" id=\"form-field-message-0\" name=\"form_fields[message]\" required=\"required\"> <label for=\"form-field-message-0\">Spuntando questo campo accetti la nostra Privacy & Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. <a href=\"https:\/\/www.bor2travel.it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 cliccando QUI<\/a><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96f05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac96f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da428a5 elementor-widget elementor-widget-heading\" data-id=\"da428a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Restiamo connessi!!!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537d25 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3537d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d94fa2b\" href=\"https:\/\/www.instagram.com\/born2travel.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c434c3d\" href=\"https:\/\/www.facebook.com\/Born2travelit\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-75693d7\" href=\"https:\/\/www.youtube.com\/channel\/UCXjLtjiN1TpNgwwNMupe08g\/featured?view_as=subscriber\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tripadvisor elementor-repeater-item-a9d1575\" href=\"https:\/\/www.tripadvisor.co.uk\/Profile\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tripadvisor<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-58816f5\" href=\"https:\/\/twitter.com\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22354f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22354f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c34d34 elementor-widget elementor-widget-heading\" data-id=\"0c34d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">Assicurazione di viaggio: \n\nmai partire senza!\nNoi consigliamo: Chapka!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b38e43 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3b38e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"150\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png\" class=\"attachment-large size-large wp-image-23587\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png 153w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka-12x12.png 12w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2c124 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3c2c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">sconto del 10% <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc07bc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc07bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07cf481 elementor-widget elementor-widget-heading\" data-id=\"07cf481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.instagram.com\/born2travel.it\">Seguici su INSTAGRAM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817df7 elementor-widget elementor-widget-shortcode\" data-id=\"b817df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>Questo errore \u00e8 visibile solamente agli amministratori WordPress<\/span><br\/>\n\t\t\t<p><strong>Errore: Nessun feed trovato.<\/strong>\n\t\t\t<p>Vai alla pagina delle impostazioni del feed di Instagram per creare un feed.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210cc6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"210cc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f08535 elementor-widget elementor-widget-heading\" data-id=\"4f08535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Born2travel - VIDEO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf5def elementor-widget elementor-widget-video\" data-id=\"0bf5def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_k7oz8Hnxhk&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82826af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82826af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef49e70 elementor-widget elementor-widget-heading\" data-id=\"ef49e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ultimi Articoli dal Blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006a30 elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"0006a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31634 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-macao tag-asia tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-macao tag-travel tag-travel-with-kids\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/macao\/\">\n\t\t\t\tMacao in due giorni: Tra fascino portoghese e luci da &#8220;Las Vegas d&#8217;Oriente&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31467 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-calcutta category-ganges category-india category-indian-ocean category-kolkata category-travel category-travel-with-kids tag-asia tag-backpacking tag-born2travel-it tag-born2travelit tag-calcutta tag-kolkata tag-mother-teresa tag-sundarbans tag-tigers tag-travel tag-west-bengala\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/calcutta\/\">\n\t\t\t\tCalcutta &#8211; Il battito profondo dell&#8217;India\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29309 post type-post status-publish format-standard has-post-thumbnail hentry category-africa category-albania category-almaty category-argentina category-backpacking-around-the-world category-baku category-bali category-bangkok category-born2travel category-born2travel-it category-born2travelit category-brasile category-bristol category-budapest category-cina category-citta-europee category-cracovia category-dolomiti category-europa category-europe category-firenze category-francia category-greece category-grenada category-honeymoon category-hong-kong category-indonesia category-islanda category-italia category-parigi category-ryadh category-st-moritz category-stati-uniti category-travel category-travel-with-kids category-trentino-alto-adige category-turchia category-turkey category-tuscany tag-backpacking tag-born2travel-it tag-born2travelit tag-cruise tag-europa tag-europe tag-honeymoon tag-luxury tag-parigi tag-ryadh tag-st-moritz tag-travel tag-travel-in-europe tag-viaggi-lussuosi tag-volo-privato\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/fughe-di-lusso\/\">\n\t\t\t\tFughe di lusso: rotte dirette verso destinazioni d&#8217;\u00e9lite\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29234 post type-post status-publish format-standard has-post-thumbnail hentry category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-citta-europee category-madrid category-spagna tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-cose-da-fare-a-madrid tag-europa tag-europe tag-madrid tag-viaggio-a-madrid tag-viaggio-in-spagna tag-week-end-a-madrid\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/it\/le-5-cose-migliori-da-fare-in-vacanza-a-madrid\/\">\n\t\t\t\tMadrid &#8211; Le 5 cose migliori da fare in vacanza a Madrid\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ca7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f16ca7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nepal Capitale: Katmandu Moneta: Rupia Periodo migliore: Ottobre e novembre<\/p>\n","protected":false},"author":2,"featured_media":1031,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[52,103,104,120,121,122,621,41,682,681,173,83],"tags":[55,36,59,60,259,692,684,690,693,686,683,691,32,685,88,689,688,687],"class_list":["post-16216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-backpacking","category-backpacking-around-the-world","category-born2travel","category-born2travel-it","category-born2travelit","category-couchsurfing","category-diari-di-viaggio","category-himalaya","category-nepal","category-travel","category-travel-with-kids","tag-asia","tag-backpacking","tag-born2travel","tag-born2travel-it","tag-born2travelit","tag-everest","tag-himalaya","tag-katmandu","tag-lumbini","tag-namaste","tag-nepal","tag-pokhara","tag-travel","tag-travel-to-nepal","tag-travel-with-kids","tag-trekking","tag-trekking-to-nepal","tag-viaggio-in-nepal"],"_links":{"self":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/16216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/comments?post=16216"}],"version-history":[{"count":5,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/16216\/revisions"}],"predecessor-version":[{"id":19731,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/posts\/16216\/revisions\/19731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/media\/1031"}],"wp:attachment":[{"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/media?parent=16216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/categories?post=16216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/born2travel.it\/it\/wp-json\/wp\/v2\/tags?post=16216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}