{"id":28045,"date":"2024-01-24T10:58:34","date_gmt":"2024-01-24T10:58:34","guid":{"rendered":"http:\/\/born2travel.it\/?p=28045"},"modified":"2025-01-31T11:17:54","modified_gmt":"2025-01-31T11:17:54","slug":"villaggio-di-babbo-natale","status":"publish","type":"post","link":"https:\/\/born2travel.it\/en\/villaggio-di-babbo-natale\/","title":{"rendered":"Lapland \u2013 To Santa Claus' village"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"28045\" class=\"elementor elementor-28045\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2da889e7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2da889e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c0017b\" data-id=\"6c0017b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13974861 elementor-widget elementor-widget-menu-anchor\" data-id=\"13974861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-121e566b elementor-skin-carousel elementor-widget elementor-widget-media-carousel\" data-id=\"121e566b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"santa claus (2)\" style=\"background-image: url(&#039;https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-712913fd elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"712913fd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11ec75a5\" data-id=\"11ec75a5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-398ffddc elementor-widget elementor-widget-heading\" data-id=\"398ffddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rovaniemi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca4f9a2 elementor-widget elementor-widget-text-editor\" data-id=\"6ca4f9a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Digita qui...\">Viaggio in Lapponia al villaggio di babbo natale<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45bdb2cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45bdb2cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-490a8295\" data-id=\"490a8295\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50545c71 elementor-widget elementor-widget-heading\" data-id=\"50545c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Questo pi\u00f9 che un articolo di viaggio \u00e8 una vera favola... \nVi racconter\u00f2, infatti, di quando i nostri bimbi sono riusciti a realizzare un sogno grande, forse tra \ni pi\u00f9 grandi di sempre.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b16098a elementor-widget elementor-widget-text-editor\" data-id=\"1b16098a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ma partiamo dal principio.<\/p><p>La notte del 24 dicembre, dopo aver lasciato latte e biscotti a Babbo Natale, Nora e Jago (i miei figli) sono andati a letto sognanti e speranzosi come ogni bimbo del mondo.<\/p><p>L&#8217;indomani non stavano pi\u00f9 nella pelle. La voglia di andare a vedere se sotto l&#8217;albero avrebbero ricevuto i doni tanto attesi era alle stelle. Entrarono nella sala, in punta di piedi. Gli occhi curiosi giravano a 360 gradi. Ed ecco i pacchetti tanto desiderati. Mai si sarebbero aspettati ci\u00f2 che stavano per scoprire.<\/p><p>Sotto l&#8217;albero, tra le luci colorate, una lettera stava per essere letta:<\/p><p>&#8220;Cari Nora e Jago,<\/p><p>\u00a0avrei tanta voglia di conoscervi di persona,<\/p><p>\u00a0vi aspetto a Rovaniemi (Lapponia) tra pochi giorni cos\u00ec potremo abbracciarci.<\/p><p>A presto,<\/p><p>vostro Babbo Natale&#8221;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4494fd44 elementor-widget elementor-widget-image\" data-id=\"4494fd44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"santa claus\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNjAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus.jpg\" class=\"attachment-full size-full wp-image-28060\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c80a9 elementor-widget elementor-widget-text-editor\" data-id=\"e4c80a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Inutile dire la gioia esplosa nella casa al pensiero dell\u2019incontro con Babbo Natale nel villaggio di Babbo Natale. La felicit\u00e0 la si poteva toccare.<\/p><p>&#8220;Bene ora si deve partire&#8221; dissi a gran voce.<\/p><p>&#8220;Andiamo a preparare gli zaini che ci aspetta una persona importante.&#8221;<\/p><p>Detto fatto pochi giorni dopo partivamo alla volta della Lapponia. In poco pi\u00f9 di 3 ore e mezzo atterravamo a Rovaniemi, nella Lapponia finlandese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57e8bda3 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"57e8bda3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-28045 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"57e8bda3\" data-elementor-lightbox-title=\"santa claus (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNzEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTMuanBnIiwic2xpZGVzaG93IjoiNTdlOGJkYTMifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3.jpg'><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"57e8bda3\" data-elementor-lightbox-title=\"santa claus 1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNzIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTEuanBnIiwic2xpZGVzaG93IjoiNTdlOGJkYTMifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1.jpg'><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72edb1d8 elementor-widget elementor-widget-text-editor\" data-id=\"72edb1d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il grande giorno \u00e8 arrivato. Oggi\u00a0abbiamo potuto raggiungere il villaggio di Babbo Natale presto la mattina, prima dell&#8217;arrivo di tutti i gruppi e non. Avere l&#8217;opportunit\u00e0 di fare le prime impronte sulla neve fresca davanti alla casa di Babbo natale non \u00e8 cosa da poco. Emozionati ci dirigiamo verso la casa dal tetto a punta.<\/p><p>\u00a0Nora mi guarda con gli occhi pieni di gioia per dirmi &#8220;ci siamo mamma&#8230; il momento \u00e8 arrivato&#8230;&#8221;<\/p><p>Spingiamo una grande porta in legno.\u00a0 Luci di Natale, pacchetti qua e l\u00e0.<\/p><p>Degli elfi scappano dietro ad un mobile. Altri ci indicano la strada da seguire.<\/p><p>Il percorso \u00e8 fatto da una passerella in legno con ai bordi montagne di pacchetti infiocchettati.<\/p><p>Ad un certo punto, Giorgio di <a href=\"https:\/\/www.giverviaggi.com\/\" target=\"_blank\" rel=\"noopener\">Giver Viaggi<\/a>, detto &#8220;il gigante buono&#8221;, fa segno ai bambini di guardare dentro ad un piccolo spioncino.<\/p><p>I bimbi pi\u00f9 grandi si curvano, i pi\u00f9 piccoli salgono su uno sgabellino con un occhietto chiuso e l&#8217;altro ben aperto per guardare dentro alla piccola lente tonda.<\/p><p>Cosa c&#8217;era dall&#8217;altra parte non lo sapr\u00f2 mai&#8230; perch\u00e8 solo i bimbi hanno avuto modo di vedere e, come tutti i segreti, non vanno raccontati.<\/p><p>(Ho provato a chiedere qualche giorno dopo che cosa ci fosse stato l\u00e0 dietro, ma Nora mi ha detto chiaramente che se un elfo le ha detto di non dirlo lei non l&#8217;avrebbe fatto, chiusa la questione)&#8230; mi rester\u00e0 questo dubbio per sempre&#8230; e forse mi piace pure questa cosa.<\/p><p>Attraversato il laboratorio e salite le scale ecco che ci troviamo davanti alla porta pi\u00f9 importante. L\u00e0 dietro c&#8217;\u00e8 proprio lui&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3e92b3 elementor-widget elementor-widget-image\" data-id=\"2a3e92b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"santa claus (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNzYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4.jpg\" class=\"attachment-full size-full wp-image-28076\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-4-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e59e19f elementor-widget elementor-widget-text-editor\" data-id=\"e59e19f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un elfo alla porta chiede di entrare una famiglia alla volta. Tocca a noi.<\/p><p>Un fragoroso &#8220;Buongiorno! come state?&#8221; ci accoglie.<\/p><p>Lo vediamo. Sorridente, grande, anzi gigante.<\/p><p>La barba lunghissima con boccoli bianchi.<\/p><p>Gli occhialini piccoli di vetro. Calze a strisce colorate in delle scarpe enormi. Mani grandi e forti.<\/p><p>Nora non ha detto una parola. Lo guardava curiosa ed emozionata. Aveva gli occhi ancor pi\u00f9 grandi del solito. E&#8217; riuscita a dargli un disegno che aveva fatto per lui qualche giorno prima. Jago che con la coda dell&#8217;occhio ha intravisto il suo elfo (quello che ogni anno gli viene far visita a casa nel mese di dicembre). Babbo Natale sa parlare tutte le lingue del mondo.<\/p><p>Mentre eravamo a chiacchierare con lui un elfo ci ha fatto un video e scattato foto.<\/p><p>(1 foto stampata 35 euro, 4 foto digitali pi\u00f9 l&#8217;intero video: 70 euro).<\/p><p>C&#8217;\u00e8 anche la possibilit\u00e0 che Babbo Natale dia un regalo al bambino, magari proprio quello tanto atteso. (basta accordarsi prima di entrare).<\/p><p>Noi essendoci andati nel periodo di Capodanno, era gi\u00e0 passato da casa la notte del 24.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-695b282f elementor-widget elementor-widget-image\" data-id=\"695b282f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"santa claus (5)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwODAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTUuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5.jpg\" class=\"attachment-full size-full wp-image-28080\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-5-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab5a5d2 elementor-widget elementor-widget-text-editor\" data-id=\"4ab5a5d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un&#8217;emozione bellissima, non solo per i bambini. Un momento magico che ricorderemo tutti con grande gioia.<\/p><p>Ma non \u00e8 finita qui!<\/p><p>Infatti il villaggio di Babbo Natale ha tantissime altre attrazioni, come ad esempio l&#8217;ufficio postale dove arrivano letterine da parte dei bimbi da ogni parte del mondo.<\/p><p>Ci sono molti bar e ristoranti dove prendere qualcosa di caldo tra una scoperta e l&#8217;altra.<\/p><p>Ma una delle attrazioni pi\u00f9 belle \u00e8 la linea del circolo polare artico. Proprio di fronte una <a href=\"https:\/\/santaclausvillage.info\/it\/live-video-webcam-villaggio-di-babbo-natale\/\" target=\"_blank\" rel=\"noopener\">web cam<\/a> riprende 24 ore su 24 tutto ci\u00f2 che accade e potrete salutare chi sta a casa, basta che si connetta a internet. \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c532bb0 elementor-widget elementor-widget-image\" data-id=\"c532bb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"santa claus (6)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwODYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTYuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6.jpg\" class=\"attachment-full size-full wp-image-28086\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-6-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106b7224 elementor-widget elementor-widget-text-editor\" data-id=\"106b7224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C\u2019\u00e8 una bellissima passeggiata da fare tutt&#8217;attorno dove potrete vedere le renne e volendo farci un giro (a pagamento). \u00a0<\/p><p>Credetemi, non \u00e8 semplice descrivere quello che abbiamo vissuto. E&#8217; stato intenso, magico.<\/p><p>E&#8217; come essere stati protagonisti di una fiaba.<\/p><p>Pochi viaggi resteranno impressi come questo. Il consiglio che vi d\u00f2 \u00e8 quello di andarci, magari nell&#8217;et\u00e0 &#8220;giusta&#8221; dei vostri bambini cos\u00ec da vivere ancor di pi\u00f9 tutto questo incanto.<\/p><p>Ma non \u00e8 ovviamente solo per i pi\u00f9 piccoli, anzi. Penso che la magia del Natale risieda in ognuno di noi. Penso che dovremmo cercare di credere che tutto sia possibile, che tutto si possa avverare. Se dentro di te c&#8217;\u00e8 un p\u00f2 di questa luce non ti resta che partire. Fidati non te pentirai!<\/p><p>Il consiglio che ti diamo \u00e8 quello di affidarti ad un tour operator professionale e di qualit\u00e0.<\/p><p>Buon viaggio e che la magia inizi.<\/p><p>\u00a0Stefy<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95d6b42 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"95d6b42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-28045 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"95d6b42\" data-elementor-lightbox-title=\"santa claus (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwOTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTEtMS5qcGciLCJzbGlkZXNob3ciOiI5NWQ2YjQyIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-1-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"95d6b42\" data-elementor-lightbox-title=\"santa claus (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwOTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDFcL3NhbnRhLWNsYXVzLTcuanBnIiwic2xpZGVzaG93IjoiOTVkNmI0MiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2024\/01\/santa-claus-7.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b759419\" data-id=\"5b759419\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dafa053 elementor-widget elementor-widget-shortcode\" data-id=\"6dafa053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"single\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a047c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a047c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d5e688\" data-id=\"7d5e688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4a9c79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b4a9c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iscriviti alla TRAVEL LETTER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ed75c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"12ed75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"186\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"12ed75c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"The Schengen Agreement\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"1770\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAccetto la Privacy & Coockie Policy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Spuntando questo campo accetti la nostra Privacy &amp; Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. &lt;a href=&quot;https:\/\/www.bor2travel.it\/privacy-policy\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Leggi di pi\u00f9 cliccando QUI&lt;\/a&gt;\" id=\"form-field-message-0\" name=\"form_fields[message]\" required=\"required\"> <label for=\"form-field-message-0\">Spuntando questo campo accetti la nostra Privacy & Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. <a href=\"https:\/\/www.bor2travel.it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 cliccando QUI<\/a><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96f05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac96f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da428a5 elementor-widget elementor-widget-heading\" data-id=\"da428a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Restiamo connessi!!!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537d25 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3537d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d94fa2b\" href=\"https:\/\/www.instagram.com\/born2travel.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c434c3d\" href=\"https:\/\/www.facebook.com\/Born2travelit\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-75693d7\" href=\"https:\/\/www.youtube.com\/channel\/UCXjLtjiN1TpNgwwNMupe08g\/featured?view_as=subscriber\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tripadvisor elementor-repeater-item-a9d1575\" href=\"https:\/\/www.tripadvisor.co.uk\/Profile\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tripadvisor<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-58816f5\" href=\"https:\/\/twitter.com\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22354f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22354f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c34d34 elementor-widget elementor-widget-heading\" data-id=\"0c34d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">Assicurazione di viaggio: \n\nmai partire senza!\nNoi consigliamo: Chapka!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b38e43 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3b38e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"150\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png\" class=\"attachment-large size-large wp-image-23587\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png 153w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka-12x12.png 12w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2c124 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3c2c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">sconto del 10% <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc07bc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc07bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07cf481 elementor-widget elementor-widget-heading\" data-id=\"07cf481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.instagram.com\/born2travel.it\">Seguici su INSTAGRAM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817df7 elementor-widget elementor-widget-shortcode\" data-id=\"b817df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>This error message is only visible to WordPress admins<\/span><br\/>\n\t\t\t<p><strong>Error: No feed found.<\/strong>\n\t\t\t<p>Please go to the Instagram Feed settings page to create a feed.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210cc6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"210cc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f08535 elementor-widget elementor-widget-heading\" data-id=\"4f08535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Born2travel - VIDEO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf5def elementor-widget elementor-widget-video\" data-id=\"0bf5def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_k7oz8Hnxhk&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82826af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82826af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef49e70 elementor-widget elementor-widget-heading\" data-id=\"ef49e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ultimi Articoli dal Blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006a30 elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"0006a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31634 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-macao tag-asia tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-macao tag-travel tag-travel-with-kids\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/macao\/\">\n\t\t\t\tMacao in due giorni: Tra fascino portoghese e luci da &#8220;Las Vegas d&#8217;Oriente&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31467 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-calcutta category-ganges category-india category-indian-ocean category-kolkata category-travel category-travel-with-kids tag-asia tag-backpacking tag-born2travel-it tag-born2travelit tag-calcutta tag-kolkata tag-mother-teresa tag-sundarbans tag-tigers tag-travel tag-west-bengala\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/calcutta\/\">\n\t\t\t\tCalcutta &#8211; Il battito profondo dell&#8217;India\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29309 post type-post status-publish format-standard has-post-thumbnail hentry category-africa category-albania category-almaty category-argentina category-backpacking-around-the-world category-baku category-bali category-bangkok category-born2travel category-born2travel-it category-born2travelit category-brasile category-bristol category-budapest category-cina category-citta-europee category-cracovia category-dolomiti category-europa category-europe category-firenze category-francia category-greece category-grenada category-honeymoon category-hong-kong category-indonesia category-islanda category-italia category-parigi category-ryadh category-st-moritz category-stati-uniti category-travel category-travel-with-kids category-trentino-alto-adige category-turchia category-turkey category-tuscany tag-backpacking tag-born2travel-it tag-born2travelit tag-cruise tag-europa tag-europe tag-honeymoon tag-luxury tag-parigi tag-ryadh tag-st-moritz tag-travel tag-travel-in-europe tag-viaggi-lussuosi tag-volo-privato\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/fughe-di-lusso\/\">\n\t\t\t\tFughe di lusso: rotte dirette verso destinazioni d&#8217;\u00e9lite\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29234 post type-post status-publish format-standard has-post-thumbnail hentry category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-citta-europee category-madrid category-spagna tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-cose-da-fare-a-madrid tag-europa tag-europe tag-madrid tag-viaggio-a-madrid tag-viaggio-in-spagna tag-week-end-a-madrid\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/le-5-cose-migliori-da-fare-in-vacanza-a-madrid\/\">\n\t\t\t\tMadrid &#8211; Le 5 cose migliori da fare in vacanza a Madrid\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ca7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f16ca7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39255044 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39255044\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49fc32ac\" data-id=\"49fc32ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14161e92 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14161e92\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73892c1a\" data-id=\"73892c1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1083a2ec elementor-widget elementor-widget-heading\" data-id=\"1083a2ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Scopri la citt\u00e0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30ecc466 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"30ecc466\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-382eed24\" data-id=\"382eed24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-473bf926 elementor-widget elementor-widget-google_maps\" data-id=\"473bf926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=santa%20claus%20village&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"santa claus village\"\n\t\t\t\t\taria-label=\"santa claus village\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rovaniemi Viaggio in Lapponia al villaggio di babbo natale Questo<\/p>","protected":false},"author":2,"featured_media":28058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[103,104,120,121,122,1076,1075,173,83],"tags":[1082,36,59,60,259,290,1084,1077,1081,1083,32,296],"class_list":["post-28045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backpacking","category-backpacking-around-the-world","category-born2travel","category-born2travel-it","category-born2travelit","category-finlandia","category-lapponia","category-travel","category-travel-with-kids","tag-babbo-natale","tag-backpacking","tag-born2travel","tag-born2travel-it","tag-born2travelit","tag-europa","tag-lapland","tag-lapponia","tag-rovaniemi","tag-santa-claus","tag-travel","tag-travel-in-europe"],"_links":{"self":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/28045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/comments?post=28045"}],"version-history":[{"count":5,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/28045\/revisions"}],"predecessor-version":[{"id":29870,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/28045\/revisions\/29870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media\/28058"}],"wp:attachment":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media?parent=28045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/categories?post=28045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/tags?post=28045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}