{"id":23794,"date":"2022-06-13T12:29:43","date_gmt":"2022-06-13T12:29:43","guid":{"rendered":"http:\/\/born2travel.it\/?p=23794"},"modified":"2022-10-18T13:55:04","modified_gmt":"2022-10-18T13:55:04","slug":"hong-kong","status":"publish","type":"post","link":"https:\/\/born2travel.it\/en\/hong-kong\/","title":{"rendered":"Hong Kong &#8211; Passeggiando lungo Tsim Shan Tsui"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"23794\" class=\"elementor elementor-23794\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-621b80c2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"621b80c2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-242372f\" data-id=\"242372f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-347e79b6 elementor-widget elementor-widget-menu-anchor\" data-id=\"347e79b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfa9cca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfa9cca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51e9fb5f\" data-id=\"51e9fb5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3be19cd2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3be19cd2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33eeb045\" data-id=\"33eeb045\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-226f9a9a elementor-widget elementor-widget-heading\" data-id=\"226f9a9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Hong Kong<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3afc90a2 elementor-widget elementor-widget-text-editor\" data-id=\"3afc90a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><strong>Capitale:<br \/><\/strong>Hong Kong<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Moneta:<br \/><\/strong>Dollaro Hong Kong<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Periodo migliore: <br \/><\/strong>Il periodo migliore per visitare Hong Kong\u00a0 va da marzo a maggio e da settembre a inizio novembre: si evita il gran freddo dell&#8217;inverno e il gran caldo estivo.<\/p><p style=\"text-align: left;\" align=\"center\"><strong>In una parola: <br \/><\/strong>Z\u01ceoshang h\u01ceo (buongiorno)<\/p><p style=\"text-align: left;\" align=\"center\"><b>Vaccini:<br \/><\/b>Nessuno<\/p><p style=\"text-align: left;\" align=\"center\"><b>Avvertenze:<br \/><\/b>&#8211; La citt\u00e0 \u00e8 molto popolosa e in perenne attivit\u00e0. Prenotare con largo anticipo l&#8217;accomodation.<\/p><p style=\"text-align: left;\" align=\"center\"><strong>A tavola:<br \/><\/strong>La cucina tipica cinese la fa da padrona ma ormai, quasi ovunque, grazie al suo spirito cosmopolita si pu\u00f2 trovare e gustare qualunque specialit\u00e0 mondiale occidentale ed orientale!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-59b55918\" data-id=\"59b55918\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ca91379 elementor-widget elementor-widget-image\" data-id=\"4ca91379\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-flag.png\" class=\"attachment-large size-large wp-image-23800\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-flag.png 900w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-flag-300x200.png 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-flag-768x512.png 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-flag-18x12.png 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3df068c7 elementor-widget elementor-widget-image\" data-id=\"3df068c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-map.jpg\" class=\"attachment-large size-large wp-image-23801\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-map.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-map-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-map-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-map-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76255896 elementor-widget elementor-widget-text-editor\" data-id=\"76255896\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><span style=\"font-weight: bold;\">Esperienze da vivere:<br \/><\/span>Raggiungere la sommit\u00e0 di Victoria Peak (554 mt) per godere una delle visite pi\u00f9 celebri di Hong Kong; Fare badloria fino alle prime luci dell&#8217;alba nel vivace quartiere di LKF; Inchinarsi dinanzi il maestoso Buddha sull&#8217;isola di Lantau.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6378e2f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6378e2f3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;mountains&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3dc98e22\" data-id=\"3dc98e22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3abf9c9a elementor-widget elementor-widget-heading\" data-id=\"3abf9c9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Passeggiando lungo Tsim Shan Tsui<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bae5e45 elementor-widget elementor-widget-heading\" data-id=\"6bae5e45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Hong Kong: citt\u00e0 cosmopolita, crocevia tra occidente e oriente, tra business e antiche tradizioni, armonia di grattacieli mozzafiato e natura incontaminata.  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-262b5042 elementor-widget elementor-widget-text-editor\" data-id=\"262b5042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Hong Kong, letteralmente: \u201cporto profumato\u201d, una citt\u00e0 che non dorme mai.<\/p><p style=\"text-align: left;\">Citt\u00e0 cosmopolita, crocevia tra occidente e oriente, armonia di grattacieli mozzafiato e natura incontaminata, dove la metropoli super moderna si intreccia con la tradizione. Senza ombra di dubbio, i\u00a0150 anni di influenza coloniale\u00a0e i 5000 anni di tradizione cinese\u00a0hanno dato a questa citt\u00e0 una\u00a0personalit\u00e0 unica.<\/p><p style=\"text-align: left;\">Impossibile non immergersi nel cuore della pulsante vita locale per assaporare tutto lo splendore di una sterminata\u00a0variet\u00e0\u00a0culturale\u00a0fatta ancora di singolari e caratteristiche mescolanze (anche linguistiche) tra passato coloniale e tradizione primordiale.<\/p><p style=\"text-align: left;\">Da piccolo villaggio di pescatori Hong Kong venne trasformata, sotto il dominio inglese, in un bastione di fondamentale importanza strategica per l&#8217;impero britannico nonch\u00e9 in un centro di primaria importanza commerciale e finanziaria.<\/p><p style=\"text-align: left;\">Hong Kong \u00e8 visitata spesso nei tempi ristretti di una coincidenza tra due aerei; la citt\u00e0 merita invece alcuni giorni per esser apprezzata e scoperta nelle sue mille sfaccettature.<\/p><p style=\"text-align: left;\">Da Hong Kong \u00e8 possibile andare pressoch\u00e9 ovunque. Il suo aeroporto \u00e8 servito dalle maggiori compagnie aeree del mondo ed \u00e8 un punto di ingresso ideale non solo per la citt\u00e0 bens\u00ec anche per tutto l&#8217;Estremo Oriente.<\/p><p style=\"text-align: left;\">Durante la visita a Hong Kong \u00e8 possibile fare i visti per qualunque paese nell&#8217;area.<\/p><p style=\"text-align: left;\">Non c&#8217;\u00e8 tempo per annoiarsi qui, perch\u00e9 le cose da fare sono davvero tantissime.<\/p><p style=\"text-align: left;\">Ecco 10 attivit\u00e0 che vi consigliamo di vivere qui!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262ca44c elementor-widget elementor-widget-heading\" data-id=\"262ca44c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cosa fare se trascorrerete qualche giorno ad Hong Kong?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2253cb14 elementor-widget elementor-widget-text-editor\" data-id=\"2253cb14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">1 &#8211; Victoria Peak<\/h3><p style=\"text-align: left;\">Il luogo ideale per godersi un suggestivo panorama di Hong Kong\u00a0\u00e8 senza dubbio Victoria Peak! Si tratta della vetta pi\u00f9 alta della citt\u00e0 (554 metri),\u00a0si raggiunge tramite una funicolare\u00a0in 5 minuti ma badate bene perch\u00e8 spesso le code per salire sono interminabili! Il Peak Tram (che ha pi\u00f9 di cento anni, non ha mai avuto un incidente e rappresenta un\u2019attrazione a s\u00e9) si prende \u00a0al Peak Tram Lower Terminus in Garden Road (che puoi raggiungere camminando dall\u2019uscita J2 della MTR Central Station).<\/p><p style=\"text-align: left;\">Una volta in cima,\u00a0due sono i &#8220;poli&#8221; d&#8217;interesse del promontorio: la\u00a0Peak Tower\u00a0e il\u00a0Lion Kiosk, punti preferenziali dai quali godere di favolosi panorami da copertina, sia di giorno che di notte. <br \/>Sulla Sky Terrace 428, per esempio, potrai godere di una vista di Hong Kong a 360\u00b0!<\/p><p style=\"text-align: left;\">Ti consiglio di arrivarci poco prima del tramonto in modo da poter ammirare Hong Kong che si colora di luci.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e76faf elementor-widget elementor-widget-image\" data-id=\"74e76faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"hong kong\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5MDUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong.jpg\" class=\"attachment-full size-full wp-image-24905\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3898306d elementor-widget elementor-widget-text-editor\" data-id=\"3898306d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">2 &#8211; Spettacolo \u201cA Symphony of Lights\u201d nella Avenue of Stars<\/h3><p style=\"text-align: left;\">Non stiamo parlando di uno spettacolo di luci qualunque: \u201cA Symphony of Lights\u201d \u00e8 entrato nel Guinness dei primati come lo spettacolo permanente di luci e suoni pi\u00f9 vasto del pianeta. Si tratta infatti di 45 edifici lungo la Skyline dell\u2019isola di Hong Kong che \u201csparano\u201d luci laser verso il Victoria Harbour a tempo di musica.<\/p><p style=\"text-align: left;\">Questo spettacolo si tiene ogni giorno alle 8 di sera e dura quattordici minuti.<\/p><p style=\"text-align: left;\">Nonostante lo show si svolga nell\u2019isola di Hong Kong, per ammirarlo bisogner\u00e0 arrivare sino a Kowloon. <br \/>Prendi l\u2019uscita J della MTR Tsim Sha Tsui East Station (penisola di Kowloon) e arriva sulla Tsim Sha Tsui Promenade, dall\u2019Avenue of Stars sino all\u2019Hong Kong Cultural Centre. Ti basta seguire i cartelli!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d82af7d elementor-widget elementor-widget-image\" data-id=\"d82af7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"hong kong (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5MTUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy0yLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2.jpg\" class=\"attachment-full size-full wp-image-24915\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-2-16x12.jpg 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-485746a elementor-widget elementor-widget-text-editor\" data-id=\"485746a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">3 &#8211; Visita Central, il cuore finanziario di Hong Kong<\/h3><p style=\"text-align: left;\">Il cuore finanziario di Hong Kong si chiama\u00a0Central District, in lingua locale\u00a0Chung Wan, ed \u00e8 situato nella parte nord-occidentale dell&#8217;isola. Deve il suo nome alla fermata della metropolitana &#8220;Centrale&#8221; e oggi\u00a0pu\u00f2 essere considerato la &#8220;Mecca&#8221; del lusso e del potere della citt\u00e0: qui si trovano grattacieli, lussuosi negozi e diversi palazzi importanti, come quelli che ospitano i vari consolati, come pure il Governo.<\/p><p style=\"text-align: left;\">Ma qui si trova anche un pezzo di storia: proprio in questo quartiere, difatti, imboccando Queen&#8217;s Road, si potr\u00e0 percorrere la prima strada della citt\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4db52b6 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"4db52b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-23794 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4db52b6\" data-elementor-lightbox-title=\"hong kong (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5MjIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy0xLmpwZyIsInNsaWRlc2hvdyI6IjRkYjUyYjYifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"4db52b6\" data-elementor-lightbox-title=\"hong kong (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5MjMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy0zLmpwZyIsInNsaWRlc2hvdyI6IjRkYjUyYjYifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78adec8e elementor-widget elementor-widget-text-editor\" data-id=\"78adec8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Stile1\" align=\"center\"><div class=\"Stile1\" align=\"center\"><h3 style=\"text-align: left;\">4 &#8211; Mong Kok<\/h3><p style=\"text-align: left;\">Mong Kok \u00e8 una zona\u00a0commerciale e residenziale\u00a0tra le pi\u00f9 trafficate e frenetiche di Hong Kong, ma merita sicuramente una visita, se non altro per lasciarsi contagiare dalla sua energia inarrestabile. Luci al neon,\u00a0bancarelle, centri commerciali e negozi\u00a0di vario genere animano questa area frequentata in particolare dagli appassionati di shopping in quanto proprio qui si trovano due dei mercati pi\u00f9 caratteristici della citt\u00e0 (Ladies Market e il mercato notturno di Temple Street). <br \/>Non mancano anche ristoranti, pub e un\u2019ampia scelta di\u00a0intrattenimenti.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aa67c57 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"6aa67c57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-6.jpg\" alt=\"hong kong (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-4.jpg\" alt=\"hong kong (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-8.jpg\" alt=\"hong kong (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-5.jpg\" alt=\"hong kong (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-7.jpg\" alt=\"hong kong (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-10.jpg\" alt=\"hong kong (10)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1e65e7 elementor-widget elementor-widget-text-editor\" data-id=\"4f1e65e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">5 &#8211; LKF<\/h3><p style=\"text-align: left;\">LKF, ovvero Lan Kwai Fong, \u00e8 un popolare distretto di Hong Kong che si sviluppa su una stradina dalla forma a L nel centro della citt\u00e0 e rappresenta il fulcro della\u00a0vita notturna. \u00a0Puntellato da quasi 100 locali tra\u00a0ristoranti, pub e discoteche\u00a0alla moda, \u00e8 frequentato da giovani del posto, impiegati, turisti ed expats che si ritrovano dall\u2019happy hour\u00a0fino alle prime ore del mattino. La proposta \u00e8 molto\u00a0variegata\u00a0e pensata per soddisfare ogni tipo di clientela: si spazia dai club e dai bar pi\u00f9 animati fino ai pub pi\u00f9 intimi e informali dove sorseggiare una birra e ascoltare\u00a0musica live.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356b44cb gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"356b44cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-23794 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"356b44cb\" data-elementor-lightbox-title=\"lkf (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NDMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2xrZi0yLmpwZyIsInNsaWRlc2hvdyI6IjM1NmI0NGNiIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"356b44cb\" data-elementor-lightbox-title=\"lkf (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NDIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2xrZi0xLmpwZyIsInNsaWRlc2hvdyI6IjM1NmI0NGNiIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lkf-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-247fe140 elementor-widget elementor-widget-text-editor\" data-id=\"247fe140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">6 &#8211; Nathan Road<\/h3><p style=\"text-align: left;\">Nathan Road \u00e8 la\u00a0principale via di Hong Kong\u00a0e la strada che meglio racchiude la sua essenza cosmopolita e commerciale. \u00a0\u00c8 infatti costellata da negozietti e centri commerciali, ristoranti, caffetterie e hotel di lusso. Pur essendo una delle mete predilette dagli appassionati di\u00a0shopping, lungo Natan Road si trovano anche\u00a0edifici storici: Nathan Road \u00e8 stata infatti una delle prime strade costruite nella zona di\u00a0Kowloon, dove si estende per 3 km collegando i quartieri di Tsim Sha Tsui e Sham Shui Po. Meritano una visita il leggendario\u00a0complesso Chunking Mansions,\u00a0l\u2019antica Chiesa di St. Andrew, mentre se volete rigenerarvi nel verde fate tappa al Kowloon Park.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bfa6e68 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"3bfa6e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-23794 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3bfa6e68\" data-elementor-lightbox-title=\"nathan road (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL25hdGhhbi1yb2FkLTIuanBnIiwic2xpZGVzaG93IjoiM2JmYTZlNjgifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3bfa6e68\" data-elementor-lightbox-title=\"nathan road (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NTQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL25hdGhhbi1yb2FkLTMuanBnIiwic2xpZGVzaG93IjoiM2JmYTZlNjgifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"3bfa6e68\" data-elementor-lightbox-title=\"nathan road (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NTUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL25hdGhhbi1yb2FkLTQuanBnIiwic2xpZGVzaG93IjoiM2JmYTZlNjgifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/nathan-road-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5beb4a4c elementor-widget elementor-widget-text-editor\" data-id=\"5beb4a4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">7 &#8211; Mercato notturno di Temple Street<\/h3><p style=\"text-align: left;\">Situato\u00a0nella penisola di Kowloon, il mercato notturno lungo la\u00a0Strada del Tempio, conosciuta come\u00a0Temple Street, \u00e8\u00a0uno scorcio della Hong Kong antica e autentica. Qui si riuniscono commercianti di ogni genere, dall&#8217;elettronica all&#8217;abbigliamento, dalle pietre preziose al cibo tipico, dai venditori di insetti e uccelli, fino a trovare, lungo la strada, anche numerosi chiromanti che contribuiscono a rendere mistica e suggestiva l&#8217;atmosfera.<\/p><p style=\"text-align: left;\">Gli articoli in vendita hanno prezzi per tutte le tasche e, dopo gli acquisti,\u00a0consigliamo di fermarsi a mangiare in uno dei numerosi ristoranti\u00a0per provare la frutta tropicale, i crostacei e tutti gli altri piatti tipici cantonesi. Lungo questa strada, inoltre, si trovano anche diverse vecchie cliniche dove \u00e8 possibile farsi curare ricorrendo alla medicina tradizionale cinese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23308c23 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"23308c23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-23794 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23308c23\" data-elementor-lightbox-title=\"hong kong (9)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NjIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy05LmpwZyIsInNsaWRlc2hvdyI6IjIzMzA4YzIzIn0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-9.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"23308c23\" data-elementor-lightbox-title=\"hong kong (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NjMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2hvbmcta29uZy0xMS5qcGciLCJzbGlkZXNob3ciOiIyMzMwOGMyMyJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-11.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7626496f elementor-widget elementor-widget-text-editor\" data-id=\"7626496f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">8 &#8211; Tian Tan Buddha e isola di Lantau<\/h3><p style=\"text-align: left;\">L&#8217;imponente effige di Buddha sovrasta\u00a0Ngong Ping,\u00a0sull&#8217;isola di Lantau, la pi\u00f9 larga e selvaggia di tutto il territorio\u00a0di Hong Kong, seppur la meno densamente abitata.<\/p><p style=\"text-align: left;\">La statua del\u00a0Buddha Amoghasiddhi, realizzata nel 1993 e collocata all&#8217;interno del Monastero di\u00a0Po Lin, \u00e8 in realt\u00e0\u00a0un mausoleo alto ben 34 metri\u00a0ed \u00e8 raggiungibile con una scalinata di 268 gradini! Rappresenta il simbolo dell&#8217;unione tra l&#8217;uomo e la natura. Nonostante l&#8217;impresa titanica da sostenere, il Tian Tan Buddha \u00e8\u00a0preso ogni anno d&#8217;assalto da fedeli e semplici curiosi. \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1890cf77 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1890cf77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-23794 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1890cf77\" data-elementor-lightbox-title=\"lantau (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NzMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2xhbnRhdS0xLmpwZyIsInNsaWRlc2hvdyI6IjE4OTBjZjc3In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1890cf77\" data-elementor-lightbox-title=\"lantau (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NzQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2xhbnRhdS0yLmpwZyIsInNsaWRlc2hvdyI6IjE4OTBjZjc3In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1890cf77\" data-elementor-lightbox-title=\"lantau (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5NzUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL2xhbnRhdS0zLmpwZyIsInNsaWRlc2hvdyI6IjE4OTBjZjc3In0%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/lantau-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8fcd3c elementor-widget elementor-widget-text-editor\" data-id=\"7d8fcd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">9 &#8211; Ocean Park<\/h3><p style=\"text-align: left;\">Hong Kong \u00e8 anche una delle capitali mondiali del divertimento, grazie al suo grande parco divertimenti acquatico, dove poter guidare un autoscontro e, contemporaneamente, ammirare estasiati specie faunistiche locali, dai pesci ai famosi panda.<\/p><p style=\"text-align: left;\">Il Parco \u00e8 suddiviso in due macroaree, il Waterfront e il Summit, a loro volta suddivise in otto zone di attrazione: Amazing Asian Animals, Aqua City, Whiskers Harbour, Marine World, Polar Adventure, Adventure Land, Thrill Mountain e Rainforest. Gli amanti dell&#8217;adrenalina non perderanno l&#8217;area Thrill Mountain, con almeno cinque giostre da far perdere la voce, mentre gli appassionati di animali ameranno la zone Rainforest, una foresta pluviale dove sono insediate dozzine di specie di animali differenti, che guidano i visitatori alla scoperta della biodiversit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-450bfd06 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"450bfd06\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-14.jpg\" alt=\"hong kong (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-12.jpg\" alt=\"hong kong (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-13.jpg\" alt=\"hong kong (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-20.jpg\" alt=\"hong kong (20)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-16.jpg\" alt=\"hong kong (16)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-18.jpg\" alt=\"hong kong (18)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-17.jpg\" alt=\"hong kong (17)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-19.jpg\" alt=\"hong kong (19)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/hong-kong-15.jpg\" alt=\"hong kong (15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-186e43cf elementor-widget elementor-widget-text-editor\" data-id=\"186e43cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">10 &#8211; Macao<\/h3><p style=\"text-align: left;\">A pochi passi da Hong Kong sorge la piccola: Macao.\u00a0Definita la capitale del gioco d&#8217;azzardo, non solo asiatica, ma di tutto il mondo, si contraddistingue per la particolarissima architettura urbana, di chiaro richiamo portoghese (in quanto ex-colonia del paese europeo), per una gastronomia del tutto opposta a quella di Hong Kong e per il clima tropicale molto umido, influenzato dai monsoni\u2026 ma questa \u00e8 un\u2019altra storia!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b83bb gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"29b83bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-6' class='gallery galleryid-23794 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"29b83bb\" data-elementor-lightbox-title=\"macao\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5OTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL21hY2FvLmpwZyIsInNsaWRlc2hvdyI6IjI5YjgzYmIifQ%3D%3D\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"29b83bb\" data-elementor-lightbox-title=\"macao (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ5OTIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDZcL21hY2FvLTIuanBnIiwic2xpZGVzaG93IjoiMjliODNiYiJ9\" href='https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/06\/macao-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-523d4b78\" data-id=\"523d4b78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5651f36 elementor-widget elementor-widget-shortcode\" data-id=\"5651f36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"single\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a047c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a047c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d5e688\" data-id=\"7d5e688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4a9c79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b4a9c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iscriviti alla TRAVEL LETTER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ed75c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"12ed75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"186\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"12ed75c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"St Vincent &amp; the Grenadines - Magie caraibiche a St Vincent\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"5880\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAccetto la Privacy & Coockie Policy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Spuntando questo campo accetti la nostra Privacy &amp; Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. &lt;a href=&quot;https:\/\/www.bor2travel.it\/privacy-policy\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Leggi di pi\u00f9 cliccando QUI&lt;\/a&gt;\" id=\"form-field-message-0\" name=\"form_fields[message]\" required=\"required\"> <label for=\"form-field-message-0\">Spuntando questo campo accetti la nostra Privacy & Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. <a href=\"https:\/\/www.bor2travel.it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 cliccando QUI<\/a><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96f05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac96f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da428a5 elementor-widget elementor-widget-heading\" data-id=\"da428a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Restiamo connessi!!!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537d25 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3537d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d94fa2b\" href=\"https:\/\/www.instagram.com\/born2travel.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c434c3d\" href=\"https:\/\/www.facebook.com\/Born2travelit\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-75693d7\" href=\"https:\/\/www.youtube.com\/channel\/UCXjLtjiN1TpNgwwNMupe08g\/featured?view_as=subscriber\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tripadvisor elementor-repeater-item-a9d1575\" href=\"https:\/\/www.tripadvisor.co.uk\/Profile\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tripadvisor<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-58816f5\" href=\"https:\/\/twitter.com\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22354f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22354f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c34d34 elementor-widget elementor-widget-heading\" data-id=\"0c34d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">Assicurazione di viaggio: \n\nmai partire senza!\nNoi consigliamo: Chapka!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b38e43 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3b38e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"150\" src=\"http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png\" class=\"attachment-large size-large wp-image-23587\" alt=\"\" srcset=\"http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png 153w, http:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka-12x12.png 12w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2c124 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3c2c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">sconto del 10% <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc07bc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc07bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07cf481 elementor-widget elementor-widget-heading\" data-id=\"07cf481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.instagram.com\/born2travel.it\">Seguici su INSTAGRAM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817df7 elementor-widget elementor-widget-shortcode\" data-id=\"b817df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>This error message is only visible to WordPress admins<\/span><br\/>\n\t\t\t<p><strong>Error: No feed found.<\/strong>\n\t\t\t<p>Please go to the Instagram Feed settings page to create a feed.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210cc6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"210cc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f08535 elementor-widget elementor-widget-heading\" data-id=\"4f08535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Born2travel - VIDEO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf5def elementor-widget elementor-widget-video\" data-id=\"0bf5def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_k7oz8Hnxhk&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82826af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82826af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef49e70 elementor-widget elementor-widget-heading\" data-id=\"ef49e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ultimi Articoli dal Blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006a30 elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"0006a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31634 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-macao tag-asia tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-macao tag-travel tag-travel-with-kids\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/macao\/\">\n\t\t\t\tMacao in due giorni: Tra fascino portoghese e luci da &#8220;Las Vegas d&#8217;Oriente&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31467 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-calcutta category-ganges category-india category-indian-ocean category-kolkata category-travel category-travel-with-kids tag-asia tag-backpacking tag-born2travel-it tag-born2travelit tag-calcutta tag-kolkata tag-mother-teresa tag-sundarbans tag-tigers tag-travel tag-west-bengala\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/calcutta\/\">\n\t\t\t\tCalcutta &#8211; Il battito profondo dell&#8217;India\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29309 post type-post status-publish format-standard has-post-thumbnail hentry category-africa category-albania category-almaty category-argentina category-backpacking-around-the-world category-baku category-bali category-bangkok category-born2travel category-born2travel-it category-born2travelit category-brasile category-bristol category-budapest category-cina category-citta-europee category-cracovia category-dolomiti category-europa category-europe category-firenze category-francia category-greece category-grenada category-honeymoon category-hong-kong category-indonesia category-islanda category-italia category-parigi category-ryadh category-st-moritz category-stati-uniti category-travel category-travel-with-kids category-trentino-alto-adige category-turchia category-turkey category-tuscany tag-backpacking tag-born2travel-it tag-born2travelit tag-cruise tag-europa tag-europe tag-honeymoon tag-luxury tag-parigi tag-ryadh tag-st-moritz tag-travel tag-travel-in-europe tag-viaggi-lussuosi tag-volo-privato\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/fughe-di-lusso\/\">\n\t\t\t\tFughe di lusso: rotte dirette verso destinazioni d&#8217;\u00e9lite\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29234 post type-post status-publish format-standard has-post-thumbnail hentry category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-citta-europee category-madrid category-spagna tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-cose-da-fare-a-madrid tag-europa tag-europe tag-madrid tag-viaggio-a-madrid tag-viaggio-in-spagna tag-week-end-a-madrid\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/le-5-cose-migliori-da-fare-in-vacanza-a-madrid\/\">\n\t\t\t\tMadrid &#8211; Le 5 cose migliori da fare in vacanza a Madrid\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ca7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f16ca7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hong Kong Capitale: Hong Kong Moneta: Dollaro Hong Kong Periodo<\/p>","protected":false},"author":2,"featured_media":1023,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[52,80,104,120,121,122,41,954,173,83],"tags":[55,36,59,60,259,955,32,88,956],"class_list":["post-23794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-asia-centrale","category-backpacking-around-the-world","category-born2travel","category-born2travel-it","category-born2travelit","category-diari-di-viaggio","category-hong-kong","category-travel","category-travel-with-kids","tag-asia","tag-backpacking","tag-born2travel","tag-born2travel-it","tag-born2travelit","tag-hong-kong","tag-travel","tag-travel-with-kids","tag-visit-hong-kong"],"_links":{"self":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/23794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/comments?post=23794"}],"version-history":[{"count":6,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/23794\/revisions"}],"predecessor-version":[{"id":25016,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/23794\/revisions\/25016"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media\/1023"}],"wp:attachment":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media?parent=23794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/categories?post=23794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/tags?post=23794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}