{"id":15284,"date":"2020-12-06T07:59:58","date_gmt":"2020-12-06T07:59:58","guid":{"rendered":"http:\/\/born2travel.it\/?p=15284"},"modified":"2025-12-31T08:52:21","modified_gmt":"2025-12-31T08:52:21","slug":"india-del-nord","status":"publish","type":"post","link":"https:\/\/born2travel.it\/en\/india-del-nord\/","title":{"rendered":"India del Nord &#8211; Incredible India"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"15284\" class=\"elementor elementor-15284\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65676804 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65676804\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a72f2b6\" data-id=\"7a72f2b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-268fab4d elementor-widget elementor-widget-menu-anchor\" data-id=\"268fab4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"home\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e71383f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e71383f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2879a618\" data-id=\"2879a618\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae3337f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae3337f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05debab\" data-id=\"05debab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ba3b1a elementor-widget elementor-widget-heading\" data-id=\"7ba3b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">India del Nord<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6dcf59 elementor-widget elementor-widget-text-editor\" data-id=\"b6dcf59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><strong>Capitale:<br \/><\/strong>New Delhi<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Moneta:<br \/><\/strong>Rupia<\/p><p style=\"text-align: left;\" align=\"center\"><strong>Periodo migliore: <br \/><\/strong>L&#8217;inverno (da novembre a febbraio) in genere \u00e8 il periodo migliore per visitare l&#8217;India del nord, anche se a Delhi e nelle regioni pi\u00f9 a nord la notte tende a far freddo. Da aprile a giugno il caldo \u00e8 insopportabile sia nelle pianure settentrionali sia al centro del paese: conviene puntare verso la regione Himalayana. E&#8217; consigliabile evitare le piogge monsoniche che iniziano a giugno e possono durare fino a settembre.<\/p><p style=\"text-align: left;\" align=\"center\"><strong>In una parola: <br \/><\/strong>Namaste (<em>mi inchino a te<\/em>)<\/p><p style=\"text-align: left;\" align=\"center\"><b>Vaccini:<br \/><\/b>Consigliati Antitifica, Profilassi Antimalarica (clorochino-resistente). In molte regioni, soprattutto negli stati nord-orientali, la malaria \u00e8 presente tutto l&#8217;anno sotto i 2000 m.\u00a0<\/p><p style=\"text-align: left;\" align=\"center\"><b>Avvertenze:<br \/><\/b>&#8211; L&#8217;igiene lascia a desiderare e sono comuni le malattie causate dall&#8217;acqua o dal cibo.<br \/>&#8211; Evitate cubetti di ghiaccio e succhi di frutta allungati con acqua.<br \/>&#8211; Evitate frutta e verdura crude. <br \/>&#8211; Usate solo acqua in bottiglia.<br \/>&#8211; A volte le grandi citt\u00e0 sono opprimenti: il traffico \u00e8 intenso ed \u00e8 pericoloso persino attraversare la strada.<br \/>&#8211; Occhio alle scimmie che possono rivelarsi aggressive, soprattutto a Varanasi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e1cbbc5\" data-id=\"e1cbbc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b5866a elementor-widget elementor-widget-image\" data-id=\"2b5866a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/india-flag.png\" class=\"attachment-large size-large wp-image-15290\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/india-flag.png 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/india-flag-300x225.png 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/india-flag-768x576.png 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/india-flag-16x12.png 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7de1d45 elementor-widget elementor-widget-image\" data-id=\"7de1d45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"891\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/north-india-map.jpg\" class=\"attachment-large size-large wp-image-15291\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/north-india-map.jpg 800w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/north-india-map-269x300.jpg 269w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/north-india-map-768x855.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/north-india-map-11x12.jpg 11w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dadb5e elementor-widget elementor-widget-text-editor\" data-id=\"6dadb5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\" align=\"center\"><b>A tavola:<br \/><\/b>La cucina indiana pu\u00f2 essere super piccante! Mangerete volentieri riso, naan, paratha (pane tipo piadina), chapati e lassi (bevanda allo yogurt); i giovani palati apprezzeranno pakora (verdure passate in pastella e fritte), dosa (crepes salate) e idli (tortini di riso). Tra i dessert: kheer (budino di riso) e kulfi (gelato al latte)<\/p><p style=\"text-align: left;\" align=\"center\"><span style=\"font-weight: bold;\">Esperienze da vivere:<br \/><\/span>Trascorrere giornate intere sui <em>ghat<\/em> di Varanasi, in silenzio, ammirando il Gange ed i suoi sadhu durante le abluzioni; Visitare il Templio dei topi a Deshnok; Ammirare l&#8217;alba dinanzi al Taj Mahal ad Agra<\/p><p style=\"text-align: left;\" align=\"center\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2f47b42e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f47b42e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;shape_divider_top&quot;:&quot;mountains&quot;,&quot;shape_divider_bottom&quot;:&quot;mountains&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" opacity=\"0.33\" d=\"M473,67.3c-203.9,88.3-263.1-34-320.3,0C66,119.1,0,59.7,0,59.7V0h1000v59.7 c0,0-62.1,26.1-94.9,29.3c-32.8,3.3-62.8-12.3-75.8-22.1C806,49.6,745.3,8.7,694.9,4.7S492.4,59,473,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" opacity=\"0.66\" d=\"M734,67.3c-45.5,0-77.2-23.2-129.1-39.1c-28.6-8.7-150.3-10.1-254,39.1 s-91.7-34.4-149.2,0C115.7,118.3,0,39.8,0,39.8V0h1000v36.5c0,0-28.2-18.5-92.1-18.5C810.2,18.1,775.7,67.3,734,67.3z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M766.1,28.9c-200-57.5-266,65.5-395.1,19.5C242,1.8,242,5.4,184.8,20.6C128,35.8,132.3,44.9,89.9,52.5C28.6,63.7,0,0,0,0 h1000c0,0-9.9,40.9-83.6,48.1S829.6,47,766.1,28.9z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-71e7e7f3\" data-id=\"71e7e7f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e3d0d2f elementor-widget elementor-widget-heading\" data-id=\"7e3d0d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Incredible India<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4378379d elementor-widget elementor-widget-heading\" data-id=\"4378379d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un mese alla scoperta delle regioni dell\u2019India del Nord, da Varanasi allo splendido Rajastan, tra ghat, mucche sacre, topi venerati, elefanti divini\u2026 un nuovo mondo!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-730de672 elementor-widget elementor-widget-text-editor\" data-id=\"730de672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">L\u2019India del Nord \u00e8 un complesso mosaico che accende la curiosit\u00e0, scuote i sensi e riscalda l\u2019anima di chi lo visita. L&#8217;India \u00e8 colore, spiritualit\u00e0 e sorprese, un Paese dove l&#8217;inaspettato \u00e8 una costante.<\/p><p style=\"text-align: left;\">Un viaggio in India del Nord consente di ammirare le forme sinuose del Taj Mahal di Agra e quelle dei turbanti dai colori vivaci che avvolgono il capo dei\u00a0conducenti di elefanti del Rajasthan; permette di inebriarsi con i sapori intensi ed i profumi fragranti della\u00a0cucina locale, le cui ricette e miscele di spezie risalgono ai tempi dei Maharaja; aiuta infine a comprendere la profonda spiritualit\u00e0 e la cultura millenaria del suo popolo, che caratterizzano la citt\u00e0 sacra di <a href=\"\/ganges\" target=\"_blank\" rel=\"noopener\">Varanasi<\/a> o il\u00a0<a href=\"\/punjab\" target=\"_blank\" rel=\"noopener\">Tempio d&#8217;Oro dei sikh ad Amritsar.<\/a><\/p><p style=\"text-align: left;\">Un\u00a0viaggio in India\u00a0pu\u00f2 essere impegnativo, povert\u00e0 sconvolgente, sovraffollamento e burocrazia esasperante ma se riuscirete a superare tutto questo la vostra esperienza si riveler\u00e0 indimenticabile. Tenete conto che impiegherete settimane per visitarla, ecco perch\u00e8 abbiamo deciso di dividere il nostro lungo viaggio in pi\u00f9 frammenti. Qui ci concentriamo essenzialmente sulla parte nord dell\u2019India, sorvolando un po\u2019 sul <a href=\"\/ganges\" target=\"_blank\" rel=\"noopener\">Gange<\/a> e sul <a href=\"\/punjab\" target=\"_blank\" rel=\"noopener\">Punjab<\/a> (avendo dedicato loro due reportages a s\u00e9 stanti).\u00a0<\/p><p style=\"text-align: left;\">Siamo entrati in punta di piedi, via terra, in questa nuova realt\u00e0 dal Nepal e nonostante tutto l\u2019impatto emotivo \u00e8 stato devastante!<\/p><p style=\"text-align: left;\">Abbiamo girato per mesi, in lungo ed in largo, utilizzando i pi\u00f9 disparati mezzi di trasporto ma cercando di favorire sempre i leggendari treni\u2026 Sempre in seconda classe, viaggiatori tra gli indiani, ogni viaggio in treno potrebbe dar vita ad un libro visti i magnifici incontri, le avventure e vicissitudini notturne, il risveglio tra centinaia di persone, senza privacy, dove si mangia insieme, si canta e balla insieme e ci si fa compagnia durante le tante ore di viaggio, spesso giorni interi!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b55ae87 elementor-widget elementor-widget-text-editor\" data-id=\"3b55ae87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td colspan=\"2\" width=\"652\"><p>Il nostro itinerario suggerito (30 giorni)<\/p><\/td><\/tr><tr><td width=\"234\"><p>prima settimana:<\/p><\/td><td width=\"418\"><p>Gorakpur, Varanasi (visita ai ghat)<\/p><\/td><\/tr><tr><td width=\"234\"><p>seconda settimana:<\/p><\/td><td width=\"418\"><p>Allahabad (giro in barca fino al Sangam), Khajurao (visita ai templi sacri), Agra (visita al Taj Mahal)\u00a0\u00a0<\/p><\/td><\/tr><tr><td width=\"234\"><p>terza settimana:<\/p><\/td><td width=\"418\"><p>Jaipur, Amer (visita al Castello), Delhi (visita al Tempio Gurudwara Bangla Sahib e Qutub Minar)<\/p><\/td><\/tr><tr><td width=\"234\"><p>quarta settimana:<\/p><\/td><td width=\"418\"><p>Bikaner, Deshnok (visita al Tempio dei topi), Jodhpur (visita al Forte Mehrangarh), Ajmer, Pushkar e Udaipur<\/p><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7223af elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"d7223af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\u201c\u2026penso a quanti aspetti diversi dell\u2019India ho gi\u00e0 visto e quanti ancora me ne aspettano. Le strade affollate e caotiche di Delhi, le teste piene di pidocchi dei bambini che tendono le mani per qualche rupia, gente e vacche che dormono lungo i marciapiedi e sugli sparti-traffico, lo splendore accecante del Taj Mahal, gente che sputa e scatarra sui treni di notte, i topi che escono dalle cucine dei ristoranti, gli occhi scuri e penetranti dei vecchi dal viso grinzoso, l\u2019odore di piscio e di sterco di mucca, i sadhu a torso nudo e piedi scalzi che vivono lungo i ghat di Varanasi, le intriganti e mistiche sculture del kamasutra a Khajuraho, i sari colorati come farfalle che indossano le donne sorridenti, le vecchie accovacciate nelle loro buie stanze mentre preparano da mangiare, gruppi di uomini che chiacchierano per strada o caricano i loro rickshaw fino a piegare le ruote, l\u2019odore di incenso e di fiori.\u201d  \n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">- Paola Pedrini -<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7035cb72 elementor-widget elementor-widget-heading\" data-id=\"7035cb72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.youtube.com\/watch?v=Qpsj0yU3zvA\" target=\"_blank\" rel=\"noopener\">Scopri l'India lungo il Gange in 2 minuti (Video)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6da4f7a elementor-widget elementor-widget-video\" data-id=\"6da4f7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Qpsj0yU3zvA&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62676428 elementor-widget elementor-widget-heading\" data-id=\"62676428\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">07 ottobre Gorakpur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af3dd1 elementor-widget elementor-widget-text-editor\" data-id=\"4af3dd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Siamo al confine Tra Nepal ed India, dopo un lungo viaggio in uno scomodo bus da Pokhara. Contrattiamo per un passaggio in fuoristrada fino alla prima grande citt\u00e0: Gorakpur.<\/p><p style=\"text-align: left;\">Finalmente la mistica India. <br \/>E\u2019 emozionante varcare a piedi, coi nostri zaini sulle spalle, il grande portale che annuncia: \u201cWelcome to India\u201d.<\/p><p style=\"text-align: left;\">Mai dimenticher\u00f2 l\u2019ingresso nella stazione ferroviaria di Gorakpur.<br \/>Non ho mai visto nulla del genere. Centinaia di persone accampate per terra ovunque, sdraiate a dormire sui propri sari, milioni di moscerini di ogni genere e dimensione che ti assillavano, ti saltavano addosso, ti ronzavano attorno la testa, li sentivi dappertutto: dentro la Tshirt, nei pantaloni\u2026 per non parlare poi del fetore\u2026 chiunque pisciava dove capitava, come le bestie, senza ritegno o vergogna.<br \/>Ma abbiamo altro a cui pensare. Nonostante abbiamo viaggiato tutto il giorno ci aspetta ancora la notte in cuccetta fino a Varanasi, la mitica Benares. <br \/>Il nostro primo treno notturno in India. Siamo un po\u2019 preoccupati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ab9bf0c gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"5ab9bf0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-15284 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ab9bf0c\" data-elementor-lightbox-title=\"gorakpur (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzNDAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2dvcmFrcHVyLTEuanBnIiwic2xpZGVzaG93IjoiNWFiOWJmMGMifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1.jpg\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5ab9bf0c\" data-elementor-lightbox-title=\"gorakpur\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzNDEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2dvcmFrcHVyLmpwZyIsInNsaWRlc2hvdyI6IjVhYjliZjBjIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/gorakpur.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbb40bd elementor-widget elementor-widget-heading\" data-id=\"bbb40bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">08 ottobre Varanasi (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f991089 elementor-widget elementor-widget-text-editor\" data-id=\"4f991089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Tutto a Varanasi ruota attorno al fiume sacro: il Gange. C&#8217;\u00e8 chi che qui viene a morire, chi a pregare, chi accompagna a bagnare la propria vacca sacra o chi semplicemente decide di lavare la biancheria. L&#8217;impatto con Varanasi sar\u00e0 sicuramente molto forte ma qui la dea del fiume offre la possibilit\u00e0 di uscire dall&#8217;eterno ciclo della vita e della morte.<\/p><p style=\"text-align: left;\">Scendere la grande scalinata e trovarmi di fronte al <a href=\"\/ganges\" target=\"_blank\" rel=\"noopener\">Gange<\/a> mi ha dato un\u2019emozione fortissima. Non potevo credere di essere davvero l\u00ec, proprio quel fiume visto in mille documentari. <em><br \/><\/em>L\u2019acqua \u00e8 sporchissima ma i bambini si ci tuffano dentro per giocare, altri si lavano il corpo ed i vestiti. <em><br \/><\/em>Tre ragazze scherzano serenamente ad un metro da un cadavere che galleggiava dopo la cremazione, molte famiglie non hanno abbastanza soldi per far cremare l\u2019intero corpo e quindi anche solo mezzo bruciacchiato viene gettato nel fiume\u2026<em><br \/><\/em>Ma ci\u00f2 che importa davvero \u00e8 liberare l\u2019anima e donare lo spirito al fiume sacro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cd099 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"2cd099\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-1.jpg\" alt=\"varanasi (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-2.jpg\" alt=\"varanasi (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-3.jpg\" alt=\"varanasi (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-4.jpg\" alt=\"varanasi (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-5.jpg\" alt=\"varanasi (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-6.jpg\" alt=\"varanasi (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-7.jpg\" alt=\"varanasi (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-8.jpg\" alt=\"varanasi (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-9.jpg\" alt=\"varanasi (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-10.jpg\" alt=\"varanasi (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-11.jpg\" alt=\"varanasi (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-12.jpg\" alt=\"varanasi (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/varanasi-13.jpg\" alt=\"varanasi (13)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3da9922 elementor-widget elementor-widget-text-editor\" data-id=\"3da9922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Vacche per strada, scimmie che ti saltano sulla testa, ratti che ti passano sui piedi, cani che sonnecchiano stravaccati, cagatoni di vacche ovunque, immondizia, mendicanti, storpi, lebbrosi\u2026 miseria, povert\u00e0, tristezza\u2026<\/p><p style=\"text-align: left;\">L\u2019India \u00e8 un mondo a parte, \u00e8 confusione, \u00e8 misticismo, \u00e8 caos, bisogna gustarla a piccoli sorsi se la si vuole conoscere a fondo per poi innamorarsene.<br \/>Quella di oggi \u00e8 stata solo la prima giornata ma gi\u00e0 cos\u00ec piena che ora ho bisogno di spegnere un po\u2019 il cervello per assimilare tutto ci\u00f2 che ancora brilla nei miei occhi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2dc2f3 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"a2dc2f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-2' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2dc2f3\" data-elementor-lightbox-title=\"benares (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzNzQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2JlbmFyZXMtMS5qcGciLCJzbGlkZXNob3ciOiJhMmRjMmYzIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2dc2f3\" data-elementor-lightbox-title=\"benares (12)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzNzYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2JlbmFyZXMtMTIuanBnIiwic2xpZGVzaG93IjoiYTJkYzJmMyJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-12.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a2dc2f3\" data-elementor-lightbox-title=\"benares (13)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTUzNzcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2JlbmFyZXMtMTMuanBnIiwic2xpZGVzaG93IjoiYTJkYzJmMyJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-13.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8b3eb elementor-widget elementor-widget-heading\" data-id=\"3d8b3eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">09 ottobre Varanasi (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-553e0054 elementor-widget elementor-widget-text-editor\" data-id=\"553e0054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">La sveglia suona alle 4,45. Pochi minuti dopo siamo gi\u00e0 per strada.<br \/>Non riesco a credere che alle 5 del mattino ci sia gi\u00e0 cos\u00ec tanta gente in giro ed in piena attivit\u00e0.<\/p><p style=\"text-align: left;\">Il sole sta per nascere e noi fluttuiamo silenziosamente sulla nostra barchetta, nessuno parla, osserviamo i riti sacri dei fedeli induisti che si bagnano nelle acque della \u201c<a href=\"\/ganges\" target=\"_blank\" rel=\"noopener\">Madre Ganga<\/a>\u201d.<\/p><p style=\"text-align: left;\">Piano piano ci avviciniamo al ghat principale delle cremazioni: l\u2019Assi Ghat\u2026<br \/>Ogni commento \u00e8 superfluo ma in tarda mattinata decidiamo di ritornarci, e questa volta via terra\u2026<\/p><p style=\"text-align: left;\">Alla fine trascorreremo l\u2019intera mattinata seduti sui ghat ad osservare la quotidianit\u00e0 di questo popolo&#8230;<\/p><p style=\"text-align: left;\">Camminiamo, in infradito, tra merde, fango ed ogni forma di rifiuto\u2026<br \/>Dall\u2019alto di una palazzina abbandonata osserviamo diverse cerimonie di cremazioni. L\u2019arrivo della salma avvolta in veli multicolori, la deposizione del corpo ed infine il rogo. Arrivavano tanti corpi\u2026. Del resto se bagnarsi nelle acque sacre del fiume rappresenta la purificazione di tutti i peccati, morirci diventa l\u2019aspirazione pi\u00f9 grande per ogni induista.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27c706f2 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"27c706f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-5.jpg\" alt=\"benares (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-7.jpg\" alt=\"benares (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-4.jpg\" alt=\"benares (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-2.jpg\" alt=\"benares (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-3.jpg\" alt=\"benares (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-6.jpg\" alt=\"benares (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-8.jpg\" alt=\"benares (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-9.jpg\" alt=\"benares (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-11.jpg\" alt=\"benares (11)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6efa583 elementor-widget elementor-widget-heading\" data-id=\"6efa583\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">11 ottobre Allahabad (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-632c3e9b elementor-widget elementor-widget-text-editor\" data-id=\"632c3e9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">In tre ore e mezzo di bus raggiungiamo Allahabad.<br \/>Questa citt\u00e0 \u00e8 famosa per la celebre festa hindu del \u201cKumba Mela\u201d, cerimonia che si tiene ogni sei anni e che attira milioni di induisti da tutto il mondo.<\/p><p style=\"text-align: left;\">Ci d\u00e0 il benvenuto nella sua citt\u00e0: Nitin, un avvocato dell\u2019Alta Corte Indiana.<br \/>Ci ospita, grazie a couchsurfing, nella sua bellissima villa con tanto di custode, giardiniere oltre che le tante cameriere che tanto stona con il background circostante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c03171 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"6c03171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Un uomo \u00e8 ricco in proporzione alle cose di cui riesce a fare a meno\".\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">  - Mahatma Gandhi -<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-553acdcf gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"553acdcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-3' class='gallery galleryid-15284 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"553acdcf\" data-elementor-lightbox-title=\"allahabad\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MTIsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FsbGFoYWJhZC5qcGciLCJzbGlkZXNob3ciOiI1NTNhY2RjZiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"553acdcf\" data-elementor-lightbox-title=\"benares (10)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MTMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2JlbmFyZXMtMTAtMS5qcGciLCJzbGlkZXNob3ciOiI1NTNhY2RjZiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/benares-10-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b09370 elementor-widget elementor-widget-heading\" data-id=\"1b09370\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">12 ottobre Allahabad (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29718289 elementor-widget elementor-widget-text-editor\" data-id=\"29718289\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"Stile1\" align=\"center\"><div class=\"Stile1\" align=\"center\"><p style=\"text-align: left;\">In rickshaw raggiungiamo il Sangam, il punto in cui i fiumi pi\u00f9 sacri dell\u2019India (il Gange e lo Yuna)\u00a0 incontrano uno dei fiumi mitologici dell\u2019induismo: il Saraswati.<\/p><p style=\"text-align: left;\">Questo \u00e8 davvero un posto pieno di spiritualit\u00e0. I pellegrini formavano dei cortei, le donne ballavano, si sventolavano bandiere rosse mentre gli uomini suonavano tamburi e sitar.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6511412 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"6511412\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Mantieni i tuoi pensieri positivi\nPerch\u00e9 i tuoi pensieri diventano parole\nMantieni le tue parole positive\nPerch\u00e9 le tue parole diventano i tuoi comportamenti\nMantieni i tuoi comportamenti positivi\nPerch\u00e9 i tuoi comportamenti diventano le tue abitudini\nMantieni le tue abitudini positive\nPerch\u00e9 le tue abitudini diventano i tuoi valori\nMantieni i tuoi valori positivi\nPerch\u00e9 i tuoi valori diventano il tuo destino\".\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">     - Mahatma Gandhi - <\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28346237 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"28346237\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-7.jpg\" alt=\"allahabad (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-6.jpg\" alt=\"allahabad (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-1.jpg\" alt=\"allahabad (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-2.jpg\" alt=\"allahabad (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-3.jpg\" alt=\"allahabad (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-4.jpg\" alt=\"allahabad (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/allahabad-8.jpg\" alt=\"allahabad (8)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c6113 elementor-widget elementor-widget-heading\" data-id=\"59c6113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">13 ottobre Khajuraho (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59fc7788 elementor-widget elementor-widget-text-editor\" data-id=\"59fc7788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Dopo una notte in treno in cui piano piano cerchiamo di ambientarci, giungiamo a Khajuraho. L&#8217;imponente complesso di Khajuraho oggi conserva solo 22 templi degli 85 originari. Quanto basta per\u00f2 per rendere il piccolo villaggio del Madhya Pradesh, una delle mete pi\u00f9 visitate ogni anno dai turisti che approdano nel Subcontinente. <br \/>Erette tra il 950 e il 1050, all\u2019epoca della dinastia Chandela e oggi Patrimonio dell\u2019Umanit\u00e0 Unesco, queste icone di una maestria artistica eccellente e di una imprevedibile spiritualit\u00e0 sensuale, elegante e provocante, appaiono come masse slanciate di guglie culminanti in una serie di fregi e sculture dal sapore altamente erotico e non solo\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1599c8cf gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1599c8cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-4' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1599c8cf\" data-elementor-lightbox-title=\"khajuraho (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MzgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2toYWp1cmFoby0xLmpwZyIsInNsaWRlc2hvdyI6IjE1OTljOGNmIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1599c8cf\" data-elementor-lightbox-title=\"khajuraho (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0MzksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2toYWp1cmFoby0yLmpwZyIsInNsaWRlc2hvdyI6IjE1OTljOGNmIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1599c8cf\" data-elementor-lightbox-title=\"khajuraho (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NDAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2toYWp1cmFoby0zLmpwZyIsInNsaWRlc2hvdyI6IjE1OTljOGNmIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/khajuraho-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5061ba72 elementor-widget elementor-widget-heading\" data-id=\"5061ba72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">15 ottobre Agra (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a60db55 elementor-widget elementor-widget-text-editor\" data-id=\"a60db55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Agra, piccola cittadina nell\u2019Uttar Pradesh, molto vicina a Delhi ed \u00e8 una tappa obbligata per chiunque venga in India perch\u00e9 qui sorge uno dei monumenti pi\u00f9 belli di tutto il mondo! \u00a0<\/p><p style=\"text-align: left;\">I miei occhi sono riempiti, colpiti, incantati dalla perfetta bellezza di una delle meraviglie del mondo moderno: il Taj Mahal.<br \/>Quante volte l\u2019abbiamo visto in foto, nei films, nei documentari\u2026 ora \u00e8 l\u00ec, dinanzi a noi, come un\u00a0\u00a0leone che, dopo una notte di caccia, riposa e si rilassa fiero al sole\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb50f76 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"eb50f76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-5' class='gallery galleryid-15284 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eb50f76\" data-elementor-lightbox-title=\"agra (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NTEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FncmEtMy5qcGciLCJzbGlkZXNob3ciOiJlYjUwZjc2In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eb50f76\" data-elementor-lightbox-title=\"agra (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FncmEtMi5qcGciLCJzbGlkZXNob3ciOiJlYjUwZjc2In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f5cbe81 elementor-widget elementor-widget-text-editor\" data-id=\"4f5cbe81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Mano a mano che ci si avvicina attraverso i giardini monumentali si scoprono pian piano gli incredibili intarsi del mausoleo fatti da migliaia di pietre semipreziose che formano splendide composizioni ornamentali, una capolavoro! \u00a0<\/p><p style=\"text-align: left;\">Il Taj Mahal non \u00e8 altro che una maestosa tomba del 1600 ma io lo voglio vedere come lo ha definito Stefy: \u201cun dono d\u2019amore\u201d; un omaggio alla propria amata da parte di un re innamorato che piange per il suo amore appena spirato.<br \/>Rabindranath Tagore lo descrisse come \u201cuna lacrima sulla guancia dell\u2019eternit\u00e0\u201d; Rudyard Kipling come \u201cl\u2019incarnazione della purezza\u201d mentre il suo committente, l\u2019imperatore Shah Jahan disse che faceva \u201cversare lacrime agli occhi del sole e della luna\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-274a43b3 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"274a43b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-1.jpg\" alt=\"agra (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-5.jpg\" alt=\"taj mahal (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-4.jpg\" alt=\"agra (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-8.jpg\" alt=\"agra (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-5.jpg\" alt=\"agra (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-6.jpg\" alt=\"agra (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/agra-7.jpg\" alt=\"agra (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-4.jpg\" alt=\"taj mahal (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-6.jpg\" alt=\"taj mahal (6)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e69257 elementor-widget elementor-widget-heading\" data-id=\"0e69257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">16 ottobre Agra (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6e8dc elementor-widget elementor-widget-text-editor\" data-id=\"1d6e8dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Quando puoi svegliarti senza sveglia, fare colazione sulla romanticissima terrazza del tuo alberghetto che, combinazione, \u00e8 il punto panoramico migliore della citt\u00e0, fare due passi in totale relax tra le bancarelle del locale bazar per poi finire a mangiare un thali tra i locali: allora stai davvero vivendo il viaggio!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70cea34 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"70cea34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Dobbiamo diventare il cambiamento che vogliamo vedere\".  \t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">  - Mahatma Gandhi -<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-254884ff gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"254884ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-6' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"254884ff\" data-elementor-lightbox-title=\"taj mahal (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NjYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3Rhai1tYWhhbC0yLmpwZyIsInNsaWRlc2hvdyI6IjI1NDg4NGZmIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"254884ff\" data-elementor-lightbox-title=\"taj mahal\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NjcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3Rhai1tYWhhbC5qcGciLCJzbGlkZXNob3ciOiIyNTQ4ODRmZiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"254884ff\" data-elementor-lightbox-title=\"taj mahal (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0NjUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3Rhai1tYWhhbC0xLmpwZyIsInNsaWRlc2hvdyI6IjI1NDg4NGZmIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/taj-mahal-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-215d65a elementor-widget elementor-widget-heading\" data-id=\"215d65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">17 ottobre Jaipur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f89886 elementor-widget elementor-widget-text-editor\" data-id=\"18f89886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Chiamata la citt\u00e0 rosa, Jaipur, capitale del Rajasthan, \u00e8 una delle\u00a0localit\u00e0 pi\u00f9 pittoresche dell\u2019India. Si tratta di una\u00a0citt\u00e0 che unisce moderno e antico, che deve il suo nome alla fantasiosa trovata del Maharaja Ram Singh, che nel 1876 fece\u00a0pitturare gli edifici di Jaipur di rosa, temendo che il riflesso del sole sul bianco delle facciate potesse infastidire la visita del Principe del Galles.<\/p><p style=\"text-align: left;\">Impieghiamo circa quattro ore per raggiungerla in treno.<\/p><p style=\"text-align: left;\">Siamo ospiti, grazie a <a href=\"\/couchsurfing\" target=\"_blank\" rel=\"noopener\">couchsurfing<\/a>, di Pushpendra e la sua famiglia composta da: padre, madre, fratelli, sorelle e tanta gente che passa, prende un chai, fa due chiacchiere, magari guarda un po\u2019 di telenovelas indiane e va via. Condividiamo la stanza con una ragazza di Los Angeles che \u00e8 qui per qualche mese per lavoro, crea gioielli!<\/p><p style=\"text-align: left;\">Qui abbiamo trovato pace e tranquillit\u00e0. <br \/>Siamo attorniati da magnifici templi, il pi\u00f9 bello dei quali \u00e8 lo \u201cJhagat Siromani\u201d, proprio di fronte alla \u201cnostra\u201d casa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27cc9705 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"27cc9705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-7' class='gallery galleryid-15284 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"27cc9705\" data-elementor-lightbox-title=\"jaipur (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0OTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci0yLmpwZyIsInNsaWRlc2hvdyI6IjI3Y2M5NzA1In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"27cc9705\" data-elementor-lightbox-title=\"jaipur (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU0ODksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci0xLmpwZyIsInNsaWRlc2hvdyI6IjI3Y2M5NzA1In0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8f9488 elementor-widget elementor-widget-heading\" data-id=\"c8f9488\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">18 ottobre Jaipur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-208cbc11 elementor-widget elementor-widget-text-editor\" data-id=\"208cbc11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il monumento pi\u00f9 importante da visitare si trova pochi chilometri fuori dal centro citt\u00e0 ed \u00e8 l\u2019Amber Palace<strong>,<\/strong><strong>\u00a0<\/strong>uno dei pi\u00f9 bei palazzi reali di tutto il Rajasthan. Questo palazzo arroccato su una collina era la sede dell\u2019antica capitale dello stato ed esprime al massimo la bellezza e la perfezione dell\u2019architettura rajput. Vi si accede da uno scalone monumentale (che \u00e8 possibile percorrere a piedi o su dorso di elefante, eviterei quest\u2019ultima opzione); all\u2019interno si possono visitare gli appartamenti reali del maharaja e le magnifiche terrazze panoramiche.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eec257 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"6eec257\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\u201cNon c\u2019\u00e8 bisogno di viaggiare nel tempo per essere degli storici\". \n\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">- Isaac Asimov - <\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c2655c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"35c2655c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-4.jpg\" alt=\"jaipur (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-5.jpg\" alt=\"jaipur (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-3.jpg\" alt=\"jaipur (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-6.jpg\" alt=\"jaipur (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-7.jpg\" alt=\"jaipur (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-8.jpg\" alt=\"jaipur (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-9.jpg\" alt=\"jaipur (9)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f229ea elementor-widget elementor-widget-heading\" data-id=\"6f229ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">19 ottobre Jaipur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22240d2a elementor-widget elementor-widget-text-editor\" data-id=\"22240d2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Oggi ci dedichiamo alla citt\u00e0 vecchia di Jaipur, soprattutto la parte racchiusa tra le vecchia mura. C\u2019\u00e8 l\u2019Hawa Mahal, il famoso palazzo ad alveare di 5 piani fatto costruire dal maharaja per permettere alle donne di corte di osservare la vita quotidiana della citt\u00e0 senza essere viste e l\u2019imponente\u00a0City Palace\u00a0che racchiude diversi palazzi, cortili \u00a0e giardini, un assaggio di antica India prima di ripartire alla volta della capitale del Paese! \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-049ec96 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"049ec96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\t\"Viaggiate con anima e cuore, portate un bagaglio vuoto, e non tornate finch\u00e8 non \u00e8 pieno\u201d \t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">- Anonimo - <\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6daf2873 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6daf2873\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-8' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6daf2873\" data-elementor-lightbox-title=\"jaipur (12)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MTksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci0xMi5qcGciLCJzbGlkZXNob3ciOiI2ZGFmMjg3MyJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-12.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6daf2873\" data-elementor-lightbox-title=\"jaipur (10)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MTcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci0xMC5qcGciLCJzbGlkZXNob3ciOiI2ZGFmMjg3MyJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-10.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6daf2873\" data-elementor-lightbox-title=\"jaipur (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MTgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci0xMS5qcGciLCJzbGlkZXNob3ciOiI2ZGFmMjg3MyJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-11.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1e2f4b elementor-widget elementor-widget-heading\" data-id=\"c1e2f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">20 ottobre Delhi (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76590f1e elementor-widget elementor-widget-text-editor\" data-id=\"76590f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Sono le 3,30 del mattino quando suona la sveglia del nostro cellulare.<br \/>Fuori \u00e8 buio pesto. <br \/>In tuk tuk raggiungiamo la stazione ferroviaria di Jaipur.<br \/>Jaipur by night ci mostra un altro suo aspetto, quello lontano dallo sfarzo dei palazzi rosa, vediamo la sua gente che riposa avvolta, come delle mummie, in teli bianchi per strada, sui marciapiedi, sui rickshaw, nei tuk tuk, nei taxi. \u00a0<\/p><p style=\"text-align: left;\">Il treno parte, adoro i treni indiani, un mondo parallelo in cui si viene risucchiati velocemente ed \u00e8 bello lasciarsi guidare dal flow degli eventi!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1642ed22 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1642ed22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-9' class='gallery galleryid-15284 gallery-columns-4 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1642ed22\" data-elementor-lightbox-title=\"jaipur train (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MzMsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci10cmFpbi0xLmpwZyIsInNsaWRlc2hvdyI6IjE2NDJlZDIyIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1642ed22\" data-elementor-lightbox-title=\"jaipur train (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MzQsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci10cmFpbi0yLmpwZyIsInNsaWRlc2hvdyI6IjE2NDJlZDIyIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1642ed22\" data-elementor-lightbox-title=\"jaipur train (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MzYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci10cmFpbi00LmpwZyIsInNsaWRlc2hvdyI6IjE2NDJlZDIyIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1642ed22\" data-elementor-lightbox-title=\"jaipur train (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1MzUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2phaXB1ci10cmFpbi0zLmpwZyIsInNsaWRlc2hvdyI6IjE2NDJlZDIyIn0%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jaipur-train-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a1bda1 elementor-widget elementor-widget-text-editor\" data-id=\"14a1bda1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il treno comincia\u00a0 a rallentare, stiamo entrando nei sobborghi di Delhi!<br \/>Mi affaccio dalla mia cuccetta e davanti ai miei occhi scorrono le immagini della vita quotidiana negli slums: bambini che giocano tra la spazzatura, uomini e donne che camminano rassegnati, cani rinsecchiti che riposano\u2026<\/p><p style=\"text-align: left;\">Arriviamo finalmente ad Old Delhi e dal nostro taxi vediamo in anteprima le bellezze urbane, ci colpisce subito il palese contrasto tra ricchi e poveri.<br \/>Le capitali mi affascinano particolarmente, forse perch\u00e9 \u00e8 come se le conoscessi da sempre!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7252909 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"7252909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-10' class='gallery galleryid-15284 gallery-columns-2 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7252909\" data-elementor-lightbox-title=\"delhi (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1NTEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2RlbGhpLTIuanBnIiwic2xpZGVzaG93IjoiNzI1MjkwOSJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7252909\" data-elementor-lightbox-title=\"delhi (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1NTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2RlbGhpLTEuanBnIiwic2xpZGVzaG93IjoiNzI1MjkwOSJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89d079e elementor-widget elementor-widget-text-editor\" data-id=\"89d079e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Delhi \u00e8 la\u00a0capitale dell\u2019India, una delle destinazioni principali del Paese e primo punto di entrata, grazie alla presenza del trafficato\u00a0aeroporto internazionale di Nuova Delhi.<\/p><p style=\"text-align: left;\">La citt\u00e0 \u00e8 divisa tra la\u00a0parte vecchia (Old Delhi) e quella moderna (New Delhi), entrambe visitate ogni anno da milioni di turisti provenienti da tutto il mondo. <br \/>Da vedere assolutamente \u00e8 la zona di\u00a0Chandni Chowk, dove c\u2019\u00e8 il famoso mercato di Old Delhi, per passeggiare tra i quartieri della parte antica della citt\u00e0, tra negozi, venditori ambulanti e locali specializzati nello\u00a0street food locale.<\/p><p style=\"text-align: left;\">Particolarmente interessante \u00e8 una visita al\u00a0Forte Rosso, dichiarato Patrimonio dell\u2019Umanit\u00e0 dell\u2019UNESCO, una dimora imperiale risalente al 1600, la torre vittoriana di\u00a0Qutb Minar, che simboleggia la sconfitta della dominazione Ind\u00f9, la\u00a0Tomba di Humayun\u00a0realizzata in pietra arenaria rossa e la moschea di\u00a0Jama Masjid, la pi\u00f9 grande dell\u2019Asia.<\/p><p style=\"text-align: left;\">Da scoprire a Delhi anche il Tempio Gurudwara Bhangla Sahib, dove si pratica il culto della fede Sikh, risalente al 1784 e l\u2019India Gate, l\u2019arco di trionfo di ispirazione tipicamente francese.<\/p><p style=\"text-align: left;\">Noi l&#8217;abbiamo visitato alle due di notte ed \u00e8 stato tutto molto suggestivo.<br \/>Le bianche mura di marmo si riflettono nelle acque del laghetto che lo circonda.<\/p><p style=\"text-align: left;\">I fedeli sikh dalla lunga barba e dai grandi turbanti colorati sono molto socievoli e gioviali.<br \/>Si incuriosiscono quando ci vedono e chiedono di essere fotografati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52b5f2ee elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"52b5f2ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-6.jpg\" alt=\"delhi (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-8.jpg\" alt=\"delhi (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-15.jpg\" alt=\"delhi (15)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-9.jpg\" alt=\"delhi (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-10.jpg\" alt=\"delhi (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-14.jpg\" alt=\"delhi (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-11.jpg\" alt=\"delhi (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-13.jpg\" alt=\"delhi (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-12.jpg\" alt=\"delhi (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-3.jpg\" alt=\"delhi (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/delhi-4.jpg\" alt=\"delhi (4)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d76e79 elementor-blockquote--skin-border elementor-widget elementor-widget-blockquote\" data-id=\"7d76e79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tVi ho subito sentiti come parte della mia famiglia. Non mi son mai sentita cos\u00ec vicina a qualcuno in cos\u00ec poco tempo. Ci sono persone che incontri nel corso della tua vita e ti chiedi se ci fosse una precedente connessione con loro. Ci\u00f2 rafforza la mia credenza nella reincarnazione. Da qualche parte, in qualche modo abbiamo avuto una connessione e sono cos\u00ec contenta di avervi incontrati di nuovo in questa vita. Vi voglio bene.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">Monaliza Ramani   <\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c325932 elementor-widget elementor-widget-heading\" data-id=\"7c325932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">23 ottobre Deshnok (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-489e6457 elementor-widget elementor-widget-text-editor\" data-id=\"489e6457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Decidiamo di fermarci nella piccola cittadina di Bikaner per visitare il famigerato &#8220;tempio dei topi&#8221; di Deshnok. <br \/>Ed eccoci, in tuk tuk, verso questa nuova avventura non troppo lontani dal confine con il Pakistan.<br \/>Stefy \u00e8 molto tesa. Ah ah ah<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11770650 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"11770650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-11' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"11770650\" data-elementor-lightbox-title=\"bikaner (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1ODgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2Jpa2FuZXItMy5qcGciLCJzbGlkZXNob3ciOiIxMTc3MDY1MCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"11770650\" data-elementor-lightbox-title=\"bikaner (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1ODYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2Jpa2FuZXItMS5qcGciLCJzbGlkZXNob3ciOiIxMTc3MDY1MCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"11770650\" data-elementor-lightbox-title=\"bikaner (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU1ODcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2Jpa2FuZXItMi5qcGciLCJzbGlkZXNob3ciOiIxMTc3MDY1MCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/bikaner-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39cbae72 elementor-widget elementor-widget-text-editor\" data-id=\"39cbae72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Entriamo, due topolini attraversano il piccolo cortile, facciamo due passi ed ecco una delle immagini pi\u00f9 classiche di questo posto: due piattoni pieni di latte e decine di topi a bere\u2026<\/p><p style=\"text-align: left;\">I \u201ckaba\u201d (roditori sacri) sono venerati da tanti pellegrini, infatti, secondo una leggenda hindu: la divinit\u00e0 Karni Mata chiese al Dio della morte Yama di riportare in vita il figlio di un cantastorie afflitto da questo lutto. Al rifiuto di Yama, Karni Mata fece reincarnare tutti i cantastorie deceduti sotto forma di ratti, privando cos\u00ec Yama di anime umane.<\/p><p style=\"text-align: left;\">\u00a0Non ci posso ancora credere: ho varcato la \u201cporta della loro casa\u201d.<\/p><p style=\"text-align: left;\">Mi ha colpito tanto l\u2019idea che molta gente percorreva tanti km, ore ed ore stipati in schifosi bus per portare offerte, cibo e latte ad un\u2019orda di topastri\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12efc1b4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"12efc1b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-3.jpg\" alt=\"deshnok (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-1.jpg\" alt=\"deshnok (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-5.jpg\" alt=\"deshnok (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-6.jpg\" alt=\"deshnok (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-2.jpg\" alt=\"deshnok (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-7.jpg\" alt=\"deshnok (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-10.jpg\" alt=\"deshnok (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-8.jpg\" alt=\"deshnok (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-11.jpg\" alt=\"deshnok (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-12.jpg\" alt=\"deshnok (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-13.jpg\" alt=\"deshnok (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 12\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/deshnok-15.jpg\" alt=\"deshnok (15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793d2cd elementor-widget elementor-widget-heading\" data-id=\"793d2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">25 ottobre Jodhpur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7437848e elementor-widget elementor-widget-text-editor\" data-id=\"7437848e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prendiamo l\u2019ennesimo treno per intrufolarci in un paesaggio ancora desertico, ogni tanto sbuca qualche capanna di pietre con qualche donna che accudisce una mandria di vacche sacre\u2026 attraversiamo villaggi dimenticati da tutte le divinit\u00e0 indiane\u2026<\/p><p>Giungiamo a Jodhpur, la citt\u00e0 blu, proprio nel giorno del Diwali. <br \/>Noi lo celebriamo con una romantica cenetta nell\u2019elegante \u201cKalinga Restaurant\u201d per poi finire a perderci in una delle tante pasticcerie della citt\u00e0 ad abbuffarci di \u201cgulab jamun\u201d.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c794d4 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"29c794d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-12' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"29c794d4\" data-elementor-lightbox-title=\"jodphur (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2MTYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2pvZHBodXItMS5qcGciLCJzbGlkZXNob3ciOiIyOWM3OTRkNCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"29c794d4\" data-elementor-lightbox-title=\"jodphur (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2MTcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2pvZHBodXItMi5qcGciLCJzbGlkZXNob3ciOiIyOWM3OTRkNCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"29c794d4\" data-elementor-lightbox-title=\"jodphur (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2MTgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2pvZHBodXItMy5qcGciLCJzbGlkZXNob3ciOiIyOWM3OTRkNCJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodphur-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9243f elementor-widget elementor-widget-heading\" data-id=\"3b9243f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">26 ottobre Jodhpur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55b87b37 elementor-widget elementor-widget-text-editor\" data-id=\"55b87b37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Il forte Mehrangarh costruito prima della scoperta dell\u2019America ci regala una veduta meravigliosa sulla citt\u00e0 oltre a mostrarci un frammento di ci\u00f2 che era la vita in quegli anni in questo luogo remoto.<\/p><p style=\"text-align: left;\">E\u2019 ora di immergerci nella quotidianit\u00e0 della citt\u00e0 in profondo fermento per il Diwali. <br \/>La gente si ferma ad augurarci: \u201cHappy Diwali!\u201d\u2026 \u00e8 simpatico quando addirittura riceviamo SMS di auguri dai nostri amici indiani sul nostro cellulare indiano!<\/p><p style=\"text-align: left;\">Raggiungiamo la \u201cTorre dell\u2019orologio\u201d, centro commerciale e sociale della citt\u00e0. <br \/>Centinaia di persone acquistano o vendono. <br \/>I pasticceri ed i venditori di fuochi d\u2019artificio fanno affari d\u2019oro.<\/p><p style=\"text-align: left;\">Grazie alla nostra Lonely Planet finiamo in un piccolo locale, \u201cShri Mishrilal\u201d, a bere il miglior lassi della nostra vita! Una piccola bottega che certo non brilla per l\u2019igiene ed in cui non saremmo mai entrati se non avessimo letto le ottime referenze della nostra guida, ecco un consiglio che sentiamo di dover dare: cercate i luoghi pi\u00f9 tipici e genuini quando viaggiate, vivrete di sicuro le esperienze pi\u00f9 vive e profonde del vostro viaggio!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d06c151 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3d06c151\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-1.jpg\" alt=\"jodhpur (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-2.jpg\" alt=\"jodhpur (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-3.jpg\" alt=\"jodhpur (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-4.jpg\" alt=\"jodhpur (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-5.jpg\" alt=\"jodhpur (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-6.jpg\" alt=\"jodhpur (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-8.jpg\" alt=\"jodhpur (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-10.jpg\" alt=\"jodhpur (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-11.jpg\" alt=\"jodhpur (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-12.jpg\" alt=\"jodhpur (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-13.jpg\" alt=\"jodhpur (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-14.jpg\" alt=\"jodhpur (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-15.jpg\" alt=\"jodhpur (15)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-16.jpg\" alt=\"jodhpur (16)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/jodhpur-17.jpg\" alt=\"jodhpur (17)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8671218 elementor-widget elementor-widget-heading\" data-id=\"8671218\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">29 ottobre Ajmer (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-204986a4 elementor-widget elementor-widget-text-editor\" data-id=\"204986a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Ajmer ci accoglie con la sua frenesia, il suo caos, tuk tuk che corrono in ogni direzione, mercanti che declamano la propria merce, forti odori.<br \/>Ci dirigiamo subito alla Moschea di Dargati, \u00e8 la prima volta che vedevo una moschea cos\u00ec attiva. Strapiena di fedeli che pregano.<br \/>Al di fuori una quantit\u00e0 di storpi impressionante che chiedevano l\u2019elemosina strisciando lungo la strada.<\/p><p style=\"text-align: left;\">Mentre mi aggiravo tra i vari cortili della moschea pensavo a quanto fosse importante la fede.<br \/>Quel quid che ti fa donare la tua cena o i tuoi risparmi ad una statua anche quando non hai nulla, quel quid che ti fa adorare un mucchio di topi, che ti fa bagnare nelle acque velenose di un fiume, che ti fa donare tutti i sogni, speranze e desideri nelle mani di improbabili dei multicolori e dalle mille forme, quel quid che ti fa accettare con serena rassegnazione la misera vita che hai perch\u00e9 la successiva sar\u00e0 migliore grazie a quella attuale, quel quid che ti fa privare della tua vita uccidendo altri che non la pensano come te per farti guadagnare un meraviglioso aldil\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49db178e gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"49db178e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-13' class='gallery galleryid-15284 gallery-columns-4 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"49db178e\" data-elementor-lightbox-title=\"ajmer (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2NTYsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FqbWVyLTIuanBnIiwic2xpZGVzaG93IjoiNDlkYjE3OGUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"49db178e\" data-elementor-lightbox-title=\"ajmer (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2NTUsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FqbWVyLTEuanBnIiwic2xpZGVzaG93IjoiNDlkYjE3OGUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"49db178e\" data-elementor-lightbox-title=\"ajmer (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2NTcsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FqbWVyLTMuanBnIiwic2xpZGVzaG93IjoiNDlkYjE3OGUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"49db178e\" data-elementor-lightbox-title=\"ajmer (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2NTgsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL2FqbWVyLTQuanBnIiwic2xpZGVzaG93IjoiNDlkYjE3OGUifQ%3D%3D\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/ajmer-4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8151b9 elementor-widget elementor-widget-heading\" data-id=\"f8151b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">30 ottobre Pushkar (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3bc784 elementor-widget elementor-widget-text-editor\" data-id=\"d3bc784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Pushkar \u00e8 una cittadina magica e spirituale, sede di pellegrinaggi hindu al suo famoso\u00a0tempio dedicato a Brahma\u00a0(uno dei pochi al mondo). \u00a0<\/p><p style=\"text-align: left;\">La cittadina \u00e8 veramente molto piccola, \u00e8 tutto racchiuso intorno al\u00a0lago Pushkar, si gira in un paio d\u2019ore, ma vale la pena perdersi tra i suoi vicoli e sedersi sulle sponde del lago ad ammirare quello che succede. E\u2019 popolata da santoni\/pseudo sacerdoti che si propongono di fare\u00a0riti portafortuna ai turisti.<\/p><p style=\"text-align: left;\">Data la grande spiritualit\u00e0 della citt\u00e0, a Pushkar non si mangia carne e non si beve alcol.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4466b4a4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4466b4a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-1.jpg\" alt=\"pushkar (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-2.jpg\" alt=\"pushkar (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-3.jpg\" alt=\"pushkar (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-4.jpg\" alt=\"pushkar (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-5.jpg\" alt=\"pushkar (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-6.jpg\" alt=\"pushkar (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-7.jpg\" alt=\"pushkar (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-8.jpg\" alt=\"pushkar (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-9.jpg\" alt=\"pushkar (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-10.jpg\" alt=\"pushkar (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-11.jpg\" alt=\"pushkar (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-12.jpg\" alt=\"pushkar (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-13.jpg\" alt=\"pushkar (13)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-14.jpg\" alt=\"pushkar (14)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/pushkar-15.jpg\" alt=\"pushkar (15)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c049752 elementor-widget elementor-widget-heading\" data-id=\"c049752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">02 novembre Udaipur (India)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-126bf080 elementor-widget elementor-widget-text-editor\" data-id=\"126bf080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Udaipur \u00e8 di gran lunga la citt\u00e0 pi\u00f9 romantica del Rajasthan e quella che pi\u00f9 lo rappresenta. Come Pushkar, anche in questo caso la citt\u00e0 si \u00e8 sviluppata intorno al grande lago Pichola su cui si affacciano palazzi stupendi. <br \/>Su tutti si erge il maestoso\u00a0City Palace; l\u2019antico palazzo dei maharaja \u00e8 il pi\u00f9 grande di tutto il Rajasthan ed \u00e8 talmente grande che, oltre alla parte visitabile con le varie sale reali, hanno tirato fuori ben 3 hotel di lusso!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9f6082 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"1f9f6082\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-14' class='gallery galleryid-15284 gallery-columns-3 gallery-size-medium_large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1f9f6082\" data-elementor-lightbox-title=\"udaipur (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2OTAsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3VkYWlwdXItMi5qcGciLCJzbGlkZXNob3ciOiIxZjlmNjA4MiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1f9f6082\" data-elementor-lightbox-title=\"udaipur (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2ODksInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3VkYWlwdXItMS5qcGciLCJzbGlkZXNob3ciOiIxZjlmNjA4MiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-1.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1f9f6082\" data-elementor-lightbox-title=\"udaipur (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTU2OTEsInVybCI6Imh0dHBzOlwvXC9ib3JuMnRyYXZlbC5pdFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTJcL3VkYWlwdXItOC5qcGciLCJzbGlkZXNob3ciOiIxZjlmNjA4MiJ9\" href=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8-768x576.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8-768x576.jpg 768w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8-300x225.jpg 300w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8-16x12.jpg 16w, https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-8.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48569dd0 elementor-widget elementor-widget-text-editor\" data-id=\"48569dd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">A proposito di hotel, vedrete da lontano il famosissimo\u00a0Lake Palace Hotel\u00a0al centro del lago che \u00e8 uno degli hotel pi\u00f9 romantici del mondo. Purtroppo, da qualche anno oramai, vi si pu\u00f2 accedere solo se si pernotta l\u00ec, e ha dei costi veramente proibitivi per noi umani.<\/p><p style=\"text-align: left;\">Trascorriamo qualche giorno in questa deliziosa cittadina anche per riprenderci un po\u2019 visto che a breve ripartiremo alla scoperta dell\u2019<a href=\"\/southern-india\">India del Sud<\/a>! L\u2019avventura prosegue in questa terra incredibilmente mistica!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267c4a4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"267c4a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:2000,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:200,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-4.jpg\" alt=\"udaipur (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-6.jpg\" alt=\"udaipur (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-7.jpg\" alt=\"udaipur (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-3.jpg\" alt=\"udaipur (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2020\/12\/udaipur-5.jpg\" alt=\"udaipur (5)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18393e51\" data-id=\"18393e51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3966cbba elementor-widget elementor-widget-shortcode\" data-id=\"3966cbba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"single\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88a047c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88a047c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d5e688\" data-id=\"7d5e688\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4a9c79 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"b4a9c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">iscriviti alla TRAVEL LETTER<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ed75c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"12ed75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Successivo&quot;,&quot;step_previous_label&quot;:&quot;Precedente&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nuovo modulo\" aria-label=\"Nuovo modulo\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"186\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"12ed75c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Turkmenistan - Alla Porta dell&#039;Inferno\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"31000\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAccetto la Privacy & Coockie Policy\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Spuntando questo campo accetti la nostra Privacy &amp; Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. &lt;a href=&quot;https:\/\/www.bor2travel.it\/privacy-policy\/&quot; target=&quot;_blank&quot; rel=&quot;noopener&quot;&gt;Leggi di pi\u00f9 cliccando QUI&lt;\/a&gt;\" id=\"form-field-message-0\" name=\"form_fields[message]\" required=\"required\"> <label for=\"form-field-message-0\">Spuntando questo campo accetti la nostra Privacy & Coockie Policy che puoi leggere di seguito. Iscrivendoti tramite questo form riceverai informazioni e aggiornamenti sui viaggi ed articoli pubblicati da born2travel.it . Sempre no profit. I tuoi dati non saranno mai ceduti a terzi e sarai sempre in grado di disiscriverti agendo sul pulsante disiscriviti. <a href=\"https:\/\/www.bor2travel.it\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">Leggi di pi\u00f9 cliccando QUI<\/a><\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Invia<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac96f05 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ac96f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da428a5 elementor-widget elementor-widget-heading\" data-id=\"da428a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Restiamo connessi!!!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537d25 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3537d25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-d94fa2b\" href=\"https:\/\/www.instagram.com\/born2travel.it\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c434c3d\" href=\"https:\/\/www.facebook.com\/Born2travelit\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-75693d7\" href=\"https:\/\/www.youtube.com\/channel\/UCXjLtjiN1TpNgwwNMupe08g\/featured?view_as=subscriber\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tripadvisor elementor-repeater-item-a9d1575\" href=\"https:\/\/www.tripadvisor.co.uk\/Profile\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tripadvisor<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-tripadvisor\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-58816f5\" href=\"https:\/\/twitter.com\/born2travelit\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22354f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"22354f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c34d34 elementor-widget elementor-widget-heading\" data-id=\"0c34d34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">Assicurazione di viaggio: \n\nmai partire senza!\nNoi consigliamo: Chapka!<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b38e43 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3b38e43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.chapkadirect.it\/?app=born2tr\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"150\" src=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png\" class=\"attachment-large size-large wp-image-23587\" alt=\"\" srcset=\"https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka.png 153w, https:\/\/born2travel.it\/wp-content\/uploads\/2022\/05\/chapka-12x12.png 12w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c2c124 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3c2c124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">sconto del 10% <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc07bc0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc07bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07cf481 elementor-widget elementor-widget-heading\" data-id=\"07cf481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/www.instagram.com\/born2travel.it\">Seguici su INSTAGRAM<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817df7 elementor-widget elementor-widget-shortcode\" data-id=\"b817df7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div id=\"sbi_mod_error\" >\n\t\t\t<span>This error message is only visible to WordPress admins<\/span><br\/>\n\t\t\t<p><strong>Error: No feed found.<\/strong>\n\t\t\t<p>Please go to the Instagram Feed settings page to create a feed.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210cc6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"210cc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f08535 elementor-widget elementor-widget-heading\" data-id=\"4f08535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Born2travel - VIDEO<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf5def elementor-widget elementor-widget-video\" data-id=\"0bf5def\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_k7oz8Hnxhk&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82826af elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"82826af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef49e70 elementor-widget elementor-widget-heading\" data-id=\"ef49e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ultimi Articoli dal Blog<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0006a30 elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"0006a30\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:17,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31634 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-macao tag-asia tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-macao tag-travel tag-travel-with-kids\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/macao\/\">\n\t\t\t\tMacao in due giorni: Tra fascino portoghese e luci da &#8220;Las Vegas d&#8217;Oriente&#8221;\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-31467 post type-post status-publish format-standard has-post-thumbnail hentry category-asia category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-calcutta category-ganges category-india category-indian-ocean category-kolkata category-travel category-travel-with-kids tag-asia tag-backpacking tag-born2travel-it tag-born2travelit tag-calcutta tag-kolkata tag-mother-teresa tag-sundarbans tag-tigers tag-travel tag-west-bengala\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/calcutta\/\">\n\t\t\t\tCalcutta &#8211; Il battito profondo dell&#8217;India\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29309 post type-post status-publish format-standard has-post-thumbnail hentry category-africa category-albania category-almaty category-argentina category-backpacking-around-the-world category-baku category-bali category-bangkok category-born2travel category-born2travel-it category-born2travelit category-brasile category-bristol category-budapest category-cina category-citta-europee category-cracovia category-dolomiti category-europa category-europe category-firenze category-francia category-greece category-grenada category-honeymoon category-hong-kong category-indonesia category-islanda category-italia category-parigi category-ryadh category-st-moritz category-stati-uniti category-travel category-travel-with-kids category-trentino-alto-adige category-turchia category-turkey category-tuscany tag-backpacking tag-born2travel-it tag-born2travelit tag-cruise tag-europa tag-europe tag-honeymoon tag-luxury tag-parigi tag-ryadh tag-st-moritz tag-travel tag-travel-in-europe tag-viaggi-lussuosi tag-volo-privato\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/fughe-di-lusso\/\">\n\t\t\t\tFughe di lusso: rotte dirette verso destinazioni d&#8217;\u00e9lite\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-29234 post type-post status-publish format-standard has-post-thumbnail hentry category-backpacking category-backpacking-around-the-world category-born2travel category-born2travel-it category-born2travelit category-citta-europee category-madrid category-spagna tag-backpacking tag-born2travel tag-born2travel-it tag-born2travelit tag-cose-da-fare-a-madrid tag-europa tag-europe tag-madrid tag-viaggio-a-madrid tag-viaggio-in-spagna tag-week-end-a-madrid\" role=\"listitem\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/born2travel.it\/en\/le-5-cose-migliori-da-fare-in-vacanza-a-madrid\/\">\n\t\t\t\tMadrid &#8211; Le 5 cose migliori da fare in vacanza a Madrid\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ca7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f16ca7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>India del Nord Capitale: New Delhi Moneta: Rupia Periodo migliore:<\/p>","protected":false},"author":2,"featured_media":1032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[52,103,104,120,121,122,621,41,67,53,173],"tags":[55,36,59,60,259,66,56,671,267,670,32,673,672,675,674],"class_list":["post-15284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asia","category-backpacking","category-backpacking-around-the-world","category-born2travel","category-born2travel-it","category-born2travelit","category-couchsurfing","category-diari-di-viaggio","category-ganges","category-india","category-travel","tag-asia","tag-backpacking","tag-born2travel","tag-born2travel-it","tag-born2travelit","tag-ganges","tag-india","tag-india-del-nord","tag-indian-ocean","tag-northern-india","tag-travel","tag-travel-to-india","tag-viaggio-in-india","tag-viaje-en-india","tag-visit-india"],"_links":{"self":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/15284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/comments?post=15284"}],"version-history":[{"count":6,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/15284\/revisions"}],"predecessor-version":[{"id":31606,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/posts\/15284\/revisions\/31606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media\/1032"}],"wp:attachment":[{"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/media?parent=15284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/categories?post=15284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/born2travel.it\/en\/wp-json\/wp\/v2\/tags?post=15284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}